{"id":445,"date":"2024-10-06T16:27:34","date_gmt":"2024-10-06T07:27:34","guid":{"rendered":"https:\/\/g-jp.net\/main\/?p=445"},"modified":"2024-12-03T13:29:21","modified_gmt":"2024-12-03T04:29:21","slug":"post-445","status":"publish","type":"post","link":"https:\/\/g-jp.net\/main\/445.html","title":{"rendered":"\u30ac\u30f3\u30c0\u30e0 \u30b7\u30fc\u30c9 \u30c7\u30b9\u30c6\u30a3\u30cb\u30fc \u3042\u3089\u3059\u3058\u3068\u898b\u3069\u3053\u308d\u89e3\u8aac\uff01\u4e3b\u8981\u30ad\u30e3\u30e9\u306e\u5909\u5316\u3068\u7269\u8a9e\u306e\u5168\u5bb9"},"content":{"rendered":"\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/g-jp.net\/main\/445.html\/#%E3%82%AC%E3%83%B3%E3%83%80%E3%83%A0SEED_DESTINY%E3%81%AE%E3%81%82%E3%82%89%E3%81%99%E3%81%98%E3%81%A8%E4%B8%96%E7%95%8C%E8%A6%B3\" >\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u306e\u3042\u3089\u3059\u3058\u3068\u4e16\u754c\u89b3<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/g-jp.net\/main\/445.html\/#CE73%E5%B9%B4%E3%81%AE%E4%B8%96%E7%95%8C%E3%81%AF%E3%81%A9%E3%81%AE%E3%82%88%E3%81%86%E3%81%AA%E7%8A%B6%E6%B3%81%E3%81%8B%EF%BC%9F\" >C.E.73\u5e74\u306e\u4e16\u754c\u306f\u3069\u306e\u3088\u3046\u306a\u72b6\u6cc1\u304b\uff1f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/g-jp.net\/main\/445.html\/#%E5%89%8D%E4%BD%9CSEED%E3%81%8B%E3%82%89%E3%81%A9%E3%81%AE%E3%82%88%E3%81%86%E3%81%AB%E7%89%A9%E8%AA%9E%E3%81%8C%E7%99%BA%E5%B1%95%E3%81%97%E3%81%9F%E3%81%AE%E3%81%8B%EF%BC%9F\" >\u524d\u4f5cSEED\u304b\u3089\u3069\u306e\u3088\u3046\u306b\u7269\u8a9e\u304c\u767a\u5c55\u3057\u305f\u306e\u304b\uff1f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/g-jp.net\/main\/445.html\/#%E3%82%B7%E3%83%B3%E3%83%BB%E3%82%A2%E3%82%B9%E3%82%AB%E3%81%A8%E3%81%AF%EF%BC%9F%E6%96%B0%E4%B8%BB%E4%BA%BA%E5%85%AC%E3%81%AE%E8%83%8C%E6%99%AF%E3%81%A8%E5%BD%B9%E5%89%B2\" >\u30b7\u30f3\u30fb\u30a2\u30b9\u30ab\u3068\u306f\uff1f\u65b0\u4e3b\u4eba\u516c\u306e\u80cc\u666f\u3068\u5f79\u5272<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/g-jp.net\/main\/445.html\/#%E3%82%AD%E3%83%A9%E3%81%A8%E3%82%A2%E3%82%B9%E3%83%A9%E3%83%B3%E3%81%AE%E7%AB%8B%E5%A0%B4%E3%81%AF%E3%81%A9%E3%81%86%E5%A4%89%E5%8C%96%E3%81%97%E3%81%9F%E3%81%AE%E3%81%8B%EF%BC%9F\" >\u30ad\u30e9\u3068\u30a2\u30b9\u30e9\u30f3\u306e\u7acb\u5834\u306f\u3069\u3046\u5909\u5316\u3057\u305f\u306e\u304b\uff1f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/g-jp.net\/main\/445.html\/#%E3%83%87%E3%82%B9%E3%83%86%E3%82%A3%E3%83%8B%E3%83%BC%E3%83%97%E3%83%A9%E3%83%B3%E3%81%A8%E3%81%AF%EF%BC%9F%E3%81%9D%E3%81%AE%E7%9B%AE%E7%9A%84%E3%81%A8%E5%BD%B1%E9%9F%BF\" >\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30d7\u30e9\u30f3\u3068\u306f\uff1f\u305d\u306e\u76ee\u7684\u3068\u5f71\u97ff<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/g-jp.net\/main\/445.html\/#%E6%9C%80%E6%96%B0%E9%8B%AD%E3%83%A2%E3%83%93%E3%83%AB%E3%82%B9%E3%83%BC%E3%83%84%E3%81%AF%E3%81%A9%E3%81%AE%E3%82%88%E3%81%86%E3%81%AB%E6%B4%BB%E8%BA%8D%E3%81%99%E3%82%8B%E3%81%AE%E3%81%8B%EF%BC%9F\" >\u6700\u65b0\u92ed\u30e2\u30d3\u30eb\u30b9\u30fc\u30c4\u306f\u3069\u306e\u3088\u3046\u306b\u6d3b\u8e8d\u3059\u308b\u306e\u304b\uff1f<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/g-jp.net\/main\/445.html\/#%E3%82%AC%E3%83%B3%E3%83%80%E3%83%A0SEED_DESTINY%E3%81%AE%E3%81%82%E3%82%89%E3%81%99%E3%81%98%E3%83%BB%E5%9E%A3%E9%96%93%E8%A6%8B%E3%81%88%E3%82%8B%E6%B7%B1%E5%B1%A4%E3%81%A8%E8%A9%95%E4%BE%A1\" >\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u306e\u3042\u3089\u3059\u3058\u30fb\u57a3\u9593\u898b\u3048\u308b\u6df1\u5c64\u3068\u8a55\u4fa1<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/g-jp.net\/main\/445.html\/#%E4%BD%9C%E5%93%81%E3%81%8C%E5%95%8F%E3%81%84%E3%81%8B%E3%81%91%E3%82%8B%E7%A4%BE%E4%BC%9A%E5%95%8F%E9%A1%8C%E3%81%A8%E3%81%AF%EF%BC%9F\" >\u4f5c\u54c1\u304c\u554f\u3044\u304b\u3051\u308b\u793e\u4f1a\u554f\u984c\u3068\u306f\uff1f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/g-jp.net\/main\/445.html\/#%E3%81%AA%E3%81%9C%E8%A9%95%E4%BE%A1%E3%81%8C%E5%88%86%E3%81%8B%E3%82%8C%E3%82%8B%E3%81%AE%E3%81%8B%EF%BC%9F%E4%BD%9C%E5%93%81%E3%81%AE%E7%89%B9%E5%BE%B4%E3%81%A8%E6%89%B9%E8%A9%95\" >\u306a\u305c\u8a55\u4fa1\u304c\u5206\u304b\u308c\u308b\u306e\u304b\uff1f\u4f5c\u54c1\u306e\u7279\u5fb4\u3068\u6279\u8a55<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/g-jp.net\/main\/445.html\/#%E9%9F%B3%E6%A5%BD%E3%81%A8%E5%A3%B0%E5%84%AA%E9%99%A3%E3%81%AF%E3%81%A9%E3%81%AE%E3%82%88%E3%81%86%E3%81%AB%E4%BD%9C%E5%93%81%E3%82%92%E5%BD%A9%E3%82%8B%E3%81%AE%E3%81%8B%EF%BC%9F\" >\u97f3\u697d\u3068\u58f0\u512a\u9663\u306f\u3069\u306e\u3088\u3046\u306b\u4f5c\u54c1\u3092\u5f69\u308b\u306e\u304b\uff1f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/g-jp.net\/main\/445.html\/#%E3%83%95%E3%82%A1%E3%83%B3%E3%81%AF%E3%81%A9%E3%81%AE%E3%82%88%E3%81%86%E3%81%AB%E4%BD%9C%E5%93%81%E3%82%92%E6%A5%BD%E3%81%97%E3%82%93%E3%81%A7%E3%81%84%E3%82%8B%E3%81%AE%E3%81%8B%EF%BC%9F\" >\u30d5\u30a1\u30f3\u306f\u3069\u306e\u3088\u3046\u306b\u4f5c\u54c1\u3092\u697d\u3057\u3093\u3067\u3044\u308b\u306e\u304b\uff1f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/g-jp.net\/main\/445.html\/#%E9%96%A2%E9%80%A3%E5%95%86%E5%93%81%E3%81%AB%E3%81%AF%E3%81%A9%E3%81%AE%E3%82%88%E3%81%86%E3%81%AA%E3%82%82%E3%81%AE%E3%81%8C%E3%81%82%E3%82%8B%E3%81%AE%E3%81%8B%EF%BC%9F\" >\u95a2\u9023\u5546\u54c1\u306b\u306f\u3069\u306e\u3088\u3046\u306a\u3082\u306e\u304c\u3042\u308b\u306e\u304b\uff1f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/g-jp.net\/main\/445.html\/#%E6%96%B0%E4%BD%9C%E6%98%A0%E7%94%BB%E3%80%8CSEED_FREEDOM%E3%80%8D%E3%81%A7%E4%BD%95%E3%81%8C%E6%8F%8F%E3%81%8B%E3%82%8C%E3%82%8B%E3%81%AE%E3%81%8B%EF%BC%9F\" >\u65b0\u4f5c\u6620\u753b\u300cSEED FREEDOM\u300d\u3067\u4f55\u304c\u63cf\u304b\u308c\u308b\u306e\u304b\uff1f<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/g-jp.net\/main\/445.html\/#%E3%80%8C%E3%82%AC%E3%83%B3%E3%83%80%E3%83%A0SEED_DESTINY%E3%80%8D%E3%82%92%E6%A5%BD%E3%81%97%E3%82%80%E3%81%AA%E3%82%89%E2%80%A6\" >\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u3092\u697d\u3057\u3080\u306a\u3089\u2026<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/g-jp.net\/main\/445.html\/#%E3%82%AC%E3%83%B3%E3%83%80%E3%83%A0_%E3%82%B7%E3%83%BC%E3%83%89_%E3%83%87%E3%82%B9%E3%83%86%E3%82%A3%E3%83%8B%E3%83%BC_%E3%81%82%E3%82%89%E3%81%99%E3%81%98%E3%81%A8%E8%A6%8B%E3%81%A9%E3%81%93%E3%82%8D%E8%A7%A3%E8%AA%AC%EF%BC%81%E4%B8%BB%E8%A6%81%E3%82%AD%E3%83%A3%E3%83%A9%E3%81%AE%E5%A4%89%E5%8C%96%E3%81%A8%E7%89%A9%E8%AA%9E%E3%81%AE%E5%85%A8%E5%AE%B9_%E3%81%BE%E3%81%A8%E3%82%81\" >\u30ac\u30f3\u30c0\u30e0 \u30b7\u30fc\u30c9 \u30c7\u30b9\u30c6\u30a3\u30cb\u30fc \u3042\u3089\u3059\u3058\u3068\u898b\u3069\u3053\u308d\u89e3\u8aac\uff01\u4e3b\u8981\u30ad\u30e3\u30e9\u306e\u5909\u5316\u3068\u7269\u8a9e\u306e\u5168\u5bb9 \u307e\u3068\u3081<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E3%82%AC%E3%83%B3%E3%83%80%E3%83%A0SEED_DESTINY%E3%81%AE%E3%81%82%E3%82%89%E3%81%99%E3%81%98%E3%81%A8%E4%B8%96%E7%95%8C%E8%A6%B3\"><\/span>\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u306e\u3042\u3089\u3059\u3058\u3068\u4e16\u754c\u89b3<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u30ac\u30f3\u30c0\u30e0 \u30b7\u30fc\u30c9 \u30c7\u30b9\u30c6\u30a3\u30cb\u30fc \u306f\u300150\u8a71\u3082\u306e\u9577\u4e01\u5834\u3068\u3044\u3046\u4e8b\u3082\u3042\u308a\u7269\u8a9e\u306e\u5168\u5bb9\u3092\u3042\u308b\u7a0b\u5ea6\u628a\u63e1\u3057\u3066\u304a\u304f\u3053\u3068\u306f\u6642\u9593\u306b\u8ffd\u308f\u308c\u304c\u3061\u306a\u73fe\u4ee3\u751f\u6d3b\u306b\u3068\u3063\u3066\u3001\u3084\u306f\u308a\u6709\u52b9\u304b\u3082\u3057\u308c\u307e\u305b\u3093\u3002\u672c\u4f5c\u300c\u6a5f\u52d5\u6226\u58eb\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u306f\u3001\u524d\u4f5c\u300c\u30ac\u30f3\u30c0\u30e0SEED\u300d\u306e\u7d9a\u7de8\u3067\u3042\u308a\u3001\u30b3\u30fc\u30c7\u30a3\u30cd\u30fc\u30bf\u30fc\u3068\u30ca\u30c1\u30e5\u30e9\u30eb\u3068\u3044\u3046\u907a\u4f1d\u5b50\u64cd\u4f5c\u3092\u5de1\u308b\u4eba\u985e\u9593\u306e\u5bfe\u7acb\u304c\u3055\u3089\u306b\u6df1\u307e\u3063\u305fC.E.73\u5e74\u306e\u4e16\u754c\u304c\u821e\u53f0\u3002\u30b7\u30f3\u30fb\u30a2\u30b9\u30ab\u3068\u3044\u3046\u65b0\u305f\u306a\u4e3b\u4eba\u516c\u3092\u4e2d\u5fc3\u306b\u3001\u6226\u4e89\u306e\u60b2\u60e8\u3055\u3084\u500b\u4eba\u306e\u81ea\u7531\u3068\u793e\u4f1a\u79e9\u5e8f\u306e\u30d0\u30e9\u30f3\u30b9\u3092\u554f\u3044\u304b\u3051\u308b\u7269\u8a9e\u304c\u5c55\u958b\u3055\u308c\u3001\u30c7\u30e5\u30e9\u30f3\u30c0\u30eb\u8b70\u9577\u304c\u63d0\u5531\u3059\u308b\u300c\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30d7\u30e9\u30f3\u300d\u3068\u3044\u3046\u793e\u4f1a\u306e\u672a\u6765\u3092\u6c7a\u3081\u308b\u58ee\u5927\u306a\u69cb\u60f3\u304c\u7269\u8a9e\u306e\u4e2d\u6838\u3002\u767b\u5834\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u305f\u3061\u306e\u6210\u9577\u3068\u845b\u85e4\u3001\u6700\u65b0\u92ed\u306e\u30e2\u30d3\u30eb\u30b9\u30fc\u30c4\u306b\u3088\u308b\u58ee\u7d76\u306a\u6226\u95d8\u30b7\u30fc\u30f3\u3001\u305d\u3057\u3066\u30ad\u30e9\u30fb\u30e4\u30de\u30c8\u3084\u30a2\u30b9\u30e9\u30f3\u30fb\u30b6\u30e9\u3068\u3044\u3063\u305f\u524d\u4f5c\u306e\u4e3b\u4eba\u516c\u305f\u3061\u306e\u6d3b\u8e8d\u304c\u3069\u306e\u3088\u3046\u306b\u63cf\u304b\u308c\u3066\u3044\u308b\u304b\u3001\u7d50\u5c40 <strong>\u3069\u3093\u306a\u30e1\u30c7\u30a3\u30a2<\/strong>\u3092 <strong>\u3069\u3053\u3067\u898b\u305f\u3089\u304a\u5f97\u306a\u306e\u304b<\/strong> \u307e\u3067\u3092\u89e3\u8aac\u3002<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u306e\u4e16\u754c\u89b3\u3068\u3001\u5bfe\u7acb\u3059\u308b\u52e2\u529b\u306e\u72b6\u6cc1<\/li>\n\n\n\n<li>\u4e3b\u4eba\u516c\u304c\u524d\u4f5c\u304b\u3089\u5909\u66f4\u3055\u308c\u305f\u7406\u7531\u3068\u3001\u65b0\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u306e\u80cc\u666f<\/li>\n\n\n\n<li>\u524d\u4f5c\u3068\u306e\u3064\u306a\u304c\u308a\u3068\u4e3b\u8981\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u305f\u3061\u306e\u7acb\u5834\u306e\u5909\u5316<\/li>\n\n\n\n<li>\u6226\u4e89\u306e\u5f71\u97ff\u3084\u3001\u4e3b\u8981\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u305f\u3061\u304c\u62b1\u3048\u308b\u904e\u53bb\u306e\u30c8\u30e9\u30a6\u30de<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"CE73%E5%B9%B4%E3%81%AE%E4%B8%96%E7%95%8C%E3%81%AF%E3%81%A9%E3%81%AE%E3%82%88%E3%81%86%E3%81%AA%E7%8A%B6%E6%B3%81%E3%81%8B%EF%BC%9F\"><\/span>C.E.73\u5e74\u306e\u4e16\u754c\u306f\u3069\u306e\u3088\u3046\u306a\u72b6\u6cc1\u304b\uff1f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>C.E.73\u5e74\u306e\u4e16\u754c\u306f\u3001\u8868\u9762\u4e0a\u306f\u5e73\u548c\u3092\u53d6\u308a\u623b\u3057\u305f\u3088\u3046\u306b\u898b\u3048\u307e\u3059\u304c\u3001\u5b9f\u969b\u306b\u306f\u7dca\u5f35\u304c\u9ad8\u307e\u3063\u3066\u3044\u307e\u3059\u3002\u30b3\u30fc\u30c7\u30a3\u30cd\u30fc\u30bf\u30fc\uff08\u907a\u4f1d\u5b50\u64cd\u4f5c\u3055\u308c\u305f\u4eba\u9593\uff09\u3068\u30ca\u30c1\u30e5\u30e9\u30eb\uff08\u901a\u5e38\u306e\u4eba\u9593\uff09\u306e\u5bfe\u7acb\u306f\u4f9d\u7136\u3068\u3057\u3066\u7d9a\u3044\u3066\u304a\u308a\u3001\u4e21\u8005\u306e\u9593\u306b\u306f\u6839\u6df1\u3044\u6e9d\u304c\u3042\u308a\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u3053\u306e\u4e16\u754c\u3067\u306f\u3001\u5b87\u5b99\u30b3\u30ed\u30cb\u30fcPLANT\u306b\u4f4f\u3080\u30b3\u30fc\u30c7\u30a3\u30cd\u30fc\u30bf\u30fc\u3068\u3001\u5730\u7403\u306b\u4f4f\u3080\u30ca\u30c1\u30e5\u30e9\u30eb\u304c\u4e3b\u306a\u52e2\u529b\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002\u524d\u4f5c\u306e\u6226\u4e89\u304b\u30892\u5e74\u304c\u7d4c\u904e\u3057\u3001\u4e00\u898b\u5e73\u548c\u306a\u65e5\u3005\u304c\u7d9a\u3044\u3066\u3044\u308b\u3088\u3046\u306b\u898b\u3048\u307e\u3059\u304c\u3001\u305d\u306e\u88cf\u3067\u306f\u65b0\u305f\u306a\u7d1b\u4e89\u306e\u706b\u7a2e\u304c\u6f5c\u3093\u3067\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u4f8b\u3048\u3070\u3001PLANT\u306e\u8ecd\u4e8b\u7d44\u7e54ZAFT\u3068\u5730\u7403\u9023\u5408\u8ecd\u306e\u9593\u3067\u306f\u3001\u8ecd\u62e1\u7af6\u4e89\u304c\u5bc6\u304b\u306b\u9032\u884c\u3057\u3066\u3044\u307e\u3059\u3002\u307e\u305f\u3001\u4e2d\u7acb\u56fd\u30aa\u30fc\u30d6\u3082\u8907\u96d1\u306a\u7acb\u5834\u306b\u7f6e\u304b\u308c\u3066\u304a\u308a\u3001\u4e16\u754c\u306e\u5747\u8861\u3092\u4fdd\u3064\u91cd\u8981\u306a\u5f79\u5272\u3092\u62c5\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u3053\u306e\u3088\u3046\u306a\u72b6\u6cc1\u4e0b\u3067\u3001\u4eba\u3005\u306f\u904e\u53bb\u306e\u6226\u4e89\u306e\u50b7\u8de1\u3092\u7652\u3057\u3064\u3064\u3082\u3001\u65b0\u305f\u306a\u5bfe\u7acb\u306e\u53ef\u80fd\u6027\u306b\u4e0d\u5b89\u3092\u62b1\u3048\u3066\u3044\u307e\u3059\u3002C.E.73\u5e74\u306e\u4e16\u754c\u306f\u3001\u307e\u3055\u306b\u5e73\u548c\u3068\u6226\u4e89\u306e\u72ed\u9593\u306b\u3042\u308b\u4e0d\u5b89\u5b9a\u306a\u72b6\u614b\u306a\u306e\u3067\u3059\u3002<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E5%89%8D%E4%BD%9CSEED%E3%81%8B%E3%82%89%E3%81%A9%E3%81%AE%E3%82%88%E3%81%86%E3%81%AB%E7%89%A9%E8%AA%9E%E3%81%8C%E7%99%BA%E5%B1%95%E3%81%97%E3%81%9F%E3%81%AE%E3%81%8B%EF%BC%9F\"><\/span>\u524d\u4f5cSEED\u304b\u3089\u3069\u306e\u3088\u3046\u306b\u7269\u8a9e\u304c\u767a\u5c55\u3057\u305f\u306e\u304b\uff1f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u524d\u4f5c\u300c\u30ac\u30f3\u30c0\u30e0SEED\u300d\u304b\u3089\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u3078\u306e\u7269\u8a9e\u306e\u767a\u5c55\u306f\u3001\u4e3b\u306b\u4ee5\u4e0b\u306e\u70b9\u3067\u7279\u5fb4\u3065\u3051\u3089\u308c\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u307e\u305a\u3001\u4e3b\u4eba\u516c\u304c\u5909\u66f4\u3055\u308c\u307e\u3057\u305f\u3002\u524d\u4f5c\u306e\u4e3b\u4eba\u516c\u30ad\u30e9\u30fb\u30e4\u30de\u30c8\u306f\u8107\u5f79\u3068\u306a\u308a\u3001\u65b0\u305f\u306b\u30b7\u30f3\u30fb\u30a2\u30b9\u30ab\u304c\u4e2d\u5fc3\u7684\u306a\u5f79\u5272\u3092\u62c5\u3044\u307e\u3059\u3002\u3053\u306e\u3053\u3068\u306b\u3088\u308a\u3001\u7269\u8a9e\u306f\u65b0\u3057\u3044\u8996\u70b9\u304b\u3089\u5c55\u958b\u3055\u308c\u308b\u3053\u3068\u306b\u306a\u308a\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<p>\u307e\u305f\u3001\u524d\u4f5c\u3067\u63cf\u304b\u308c\u305f\u6226\u4e89\u306e\u5f71\u97ff\u304c\u8272\u6fc3\u304f\u53cd\u6620\u3055\u308c\u3066\u3044\u307e\u3059\u3002\u4f8b\u3048\u3070\u3001\u30b7\u30f3\u30fb\u30a2\u30b9\u30ab\u306f\u524d\u4f5c\u306e\u6226\u4e89\u3067\u5bb6\u65cf\u3092\u5931\u3063\u305f\u5c11\u5e74\u3067\u3042\u308a\u3001\u305d\u306e\u7d4c\u9a13\u304c\u5f7c\u306e\u884c\u52d5\u3084\u601d\u8003\u306b\u5927\u304d\u306a\u5f71\u97ff\u3092\u4e0e\u3048\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u3055\u3089\u306b\u3001\u524d\u4f5c\u3067\u63cf\u304b\u308c\u305f\u30b3\u30fc\u30c7\u30a3\u30cd\u30fc\u30bf\u30fc\u3068\u30ca\u30c1\u30e5\u30e9\u30eb\u306e\u5bfe\u7acb\u3068\u3044\u3046\u6839\u672c\u7684\u306a\u554f\u984c\u304c\u3001\u3088\u308a\u8907\u96d1\u306a\u5f62\u3067\u5c55\u958b\u3055\u308c\u307e\u3059\u3002\u7279\u306b\u3001\u30ae\u30eb\u30d0\u30fc\u30c8\u30fb\u30c7\u30e5\u30e9\u30f3\u30c0\u30eb\u8b70\u9577\u304c\u63d0\u5531\u3059\u308b\u300c\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30d7\u30e9\u30f3\u300d\u3068\u3044\u3046\u65b0\u305f\u306a\u6982\u5ff5\u304c\u5c0e\u5165\u3055\u308c\u3001\u4eba\u985e\u306e\u672a\u6765\u3092\u3081\u3050\u308b\u8b70\u8ad6\u304c\u6df1\u3081\u3089\u308c\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u4e00\u65b9\u3067\u3001\u524d\u4f5c\u304b\u3089\u306e\u7d99\u7d9a\u6027\u3082\u4fdd\u305f\u308c\u3066\u3044\u307e\u3059\u3002\u30ad\u30e9\u30fb\u30e4\u30de\u30c8\u3084\u30a2\u30b9\u30e9\u30f3\u30fb\u30b6\u30e9\u306a\u3069\u3001\u524d\u4f5c\u306e\u4e3b\u8981\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u305f\u3061\u3082\u91cd\u8981\u306a\u5f79\u5272\u3092\u679c\u305f\u3057\u3001\u5f7c\u3089\u306e\u6210\u9577\u3084\u5909\u5316\u3082\u7269\u8a9e\u306e\u91cd\u8981\u306a\u8981\u7d20\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u3053\u306e\u3088\u3046\u306b\u3001\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u306f\u524d\u4f5c\u306e\u4e16\u754c\u89b3\u3092\u8e0f\u8972\u3057\u3064\u3064\u3001\u65b0\u305f\u306a\u8996\u70b9\u3068\u554f\u984c\u63d0\u8d77\u3092\u52a0\u3048\u308b\u3053\u3068\u3067\u3001\u3088\u308a\u6df1\u307f\u306e\u3042\u308b\u7269\u8a9e\u3078\u3068\u767a\u5c55\u3057\u3066\u3044\u308b\u306e\u3067\u3059\u3002<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E3%82%B7%E3%83%B3%E3%83%BB%E3%82%A2%E3%82%B9%E3%82%AB%E3%81%A8%E3%81%AF%EF%BC%9F%E6%96%B0%E4%B8%BB%E4%BA%BA%E5%85%AC%E3%81%AE%E8%83%8C%E6%99%AF%E3%81%A8%E5%BD%B9%E5%89%B2\"><\/span>\u30b7\u30f3\u30fb\u30a2\u30b9\u30ab\u3068\u306f\uff1f\u65b0\u4e3b\u4eba\u516c\u306e\u80cc\u666f\u3068\u5f79\u5272<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u30b7\u30f3\u30fb\u30a2\u30b9\u30ab\u306f\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u306e\u65b0\u4e3b\u4eba\u516c\u3067\u3042\u308a\u3001\u8907\u96d1\u306a\u80cc\u666f\u3092\u6301\u3064\u82e5\u304d\u30d1\u30a4\u30ed\u30c3\u30c8\u3067\u3059\u3002\u5f7c\u306e\u7269\u8a9e\u306f\u3001\u4f5c\u54c1\u5168\u4f53\u306e\u30c6\u30fc\u30de\u3092\u8c61\u5fb4\u3059\u308b\u91cd\u8981\u306a\u8981\u7d20\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u30b7\u30f3\u306f\u3001\u524d\u4f5c\u306e\u6226\u4e89\u3067\u5bb6\u65cf\u3092\u5931\u3063\u305f\u5c11\u5e74\u3067\u3059\u3002\u3053\u306e\u60b2\u60e8\u306a\u7d4c\u9a13\u304c\u3001\u5f7c\u306e\u6027\u683c\u3084\u884c\u52d5\u306b\u5927\u304d\u306a\u5f71\u97ff\u3092\u4e0e\u3048\u3066\u3044\u307e\u3059\u3002\u4f8b\u3048\u3070\u3001\u6226\u4e89\u3084\u66b4\u529b\u306b\u5bfe\u3059\u308b\u5f37\u3044\u6012\u308a\u3068\u3001\u540c\u6642\u306b\u5e73\u548c\u3092\u6c42\u3081\u308b\u6c17\u6301\u3061\u3068\u3044\u3046\u3001\u76f8\u53cd\u3059\u308b\u611f\u60c5\u3092\u62b1\u3048\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u7269\u8a9e\u306e\u4e2d\u3067\u3001\u30b7\u30f3\u306fZAFT\u306e\u8ecd\u4eba\u3068\u306a\u308a\u3001\u65b0\u578b\u30e2\u30d3\u30eb\u30b9\u30fc\u30c4\u300c\u30a4\u30f3\u30d1\u30eb\u30b9\u30ac\u30f3\u30c0\u30e0\u300d\u306e\u30d1\u30a4\u30ed\u30c3\u30c8\u3068\u3057\u3066\u6d3b\u8e8d\u3057\u307e\u3059\u3002\u5f7c\u306e\u512a\u308c\u305f\u30d1\u30a4\u30ed\u30c3\u30c8\u6280\u8853\u3068\u3001\u8907\u96d1\u306a\u5fc3\u60c5\u304c\u63cf\u304b\u308c\u308b\u3053\u3068\u3067\u3001\u6226\u4e89\u306e\u73fe\u5b9f\u3068\u500b\u4eba\u306e\u845b\u85e4\u304c\u9bae\u660e\u306b\u8868\u73fe\u3055\u308c\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u30b7\u30f3\u306e\u5f79\u5272\u306f\u3001\u5358\u306a\u308b\u4e3b\u4eba\u516c\u3068\u3044\u3046\u3060\u3051\u3067\u306a\u304f\u3001\u4f5c\u54c1\u306e\u30c6\u30fc\u30de\u3067\u3042\u308b\u300c\u6226\u4e89\u3068\u5e73\u548c\u300d\u300c\u500b\u4eba\u3068\u793e\u4f1a\u300d\u306e\u554f\u984c\u3092\u4f53\u73fe\u3059\u308b\u5b58\u5728\u3067\u3059\u3002\u5f7c\u306e\u6210\u9577\u3068\u845b\u85e4\u3092\u901a\u3058\u3066\u3001\u89b3\u5ba2\u306f\u6226\u4e89\u306e\u60b2\u60e8\u3055\u3084\u3001\u7406\u60f3\u306e\u793e\u4f1a\u3068\u306f\u4f55\u304b\u3092\u8003\u3048\u3055\u305b\u3089\u308c\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u305f\u3060\u3057\u3001\u30b7\u30f3\u306e\u884c\u52d5\u3084\u6c7a\u65ad\u306b\u306f\u8cdb\u5426\u4e21\u8ad6\u304c\u3042\u308a\u3001\u305d\u308c\u304c\u4f5c\u54c1\u306e\u8a55\u4fa1\u304c\u5206\u304b\u308c\u308b\u4e00\u56e0\u306b\u3082\u306a\u3063\u3066\u3044\u307e\u3059\u3002\u5f7c\u306e\u6210\u9577\u904e\u7a0b\u3084\u5fc3\u7406\u63cf\u5199\u304c\u5341\u5206\u3067\u306f\u306a\u3044\u3068\u3044\u3046\u6279\u5224\u3082\u3042\u308a\u307e\u3059\u304c\u3001\u305d\u308c\u3086\u3048\u306b\u8996\u8074\u8005\u81ea\u8eab\u304c\u8003\u3048\u3001\u89e3\u91c8\u3059\u308b\u4f59\u5730\u3092\u6b8b\u3057\u3066\u3044\u308b\u3068\u3082\u8a00\u3048\u308b\u3067\u3057\u3087\u3046\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped coblocks-animate wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\" data-coblocks-animation=\"slideInLeft\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"339\" src=\"https:\/\/g-jp.net\/main\/wp-content\/uploads\/mega0191-640x640.jpg\" alt=\"g-jp.net\" class=\"wp-image-339\"\/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/g-jp.net\/main\/\" data-internallinksmanager029f6b8e52c=\"6\" title=\"g-jp.net\" rel=\"nofollow\">g-jp.net<\/a><\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E3%82%AD%E3%83%A9%E3%81%A8%E3%82%A2%E3%82%B9%E3%83%A9%E3%83%B3%E3%81%AE%E7%AB%8B%E5%A0%B4%E3%81%AF%E3%81%A9%E3%81%86%E5%A4%89%E5%8C%96%E3%81%97%E3%81%9F%E3%81%AE%E3%81%8B%EF%BC%9F\"><\/span>\u30ad\u30e9\u3068\u30a2\u30b9\u30e9\u30f3\u306e\u7acb\u5834\u306f\u3069\u3046\u5909\u5316\u3057\u305f\u306e\u304b\uff1f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u30ad\u30e9\u30fb\u30e4\u30de\u30c8\u3068\u30a2\u30b9\u30e9\u30f3\u30fb\u30b6\u30e9\u306f\u3001\u524d\u4f5c\u300c\u30ac\u30f3\u30c0\u30e0SEED\u300d\u306e\u4e3b\u8981\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u3067\u3057\u305f\u304c\u3001\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u3067\u306f\u5f7c\u3089\u306e\u7acb\u5834\u306b\u5927\u304d\u306a\u5909\u5316\u304c\u898b\u3089\u308c\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u30ad\u30e9\u30fb\u30e4\u30de\u30c8\u306f\u3001\u524d\u4f5c\u3067\u306f\u4e3b\u4eba\u516c\u3068\u3057\u3066\u6d3b\u8e8d\u3057\u3066\u3044\u307e\u3057\u305f\u304c\u3001\u672c\u4f5c\u3067\u306f\u7b2c\u4e09\u52e2\u529b\u56fd\u3067\u3042\u308b\u30aa\u30fc\u30d6\u3067\u96a0\u9041\u751f\u6d3b\u3092\u9001\u3063\u3066\u304a\u308a\u4e00\u6642\u7684\u306b\u8107\u5f79\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002\u3057\u304b\u3057\u3001\u7269\u8a9e\u306e\u4e2d\u76e4\u304b\u3089\u30e9\u30af\u30b9\u306e\u6697\u6bba\u672a\u9042\u4e8b\u4ef6\u3092\u6a5f\u306b\u518d\u3073 \u30d5\u30ea\u30fc\u30c0\u30e0\u30ac\u30f3\u30c0\u30e0 \u306b\u3066\u53c2\u6226\u3002\u30b7\u30f3\u30fb\u30a2\u30b9\u30ab\u306e\u30a4\u30f3\u30d1\u30eb\u30b9\u306b\u30d5\u30ea\u30fc\u30c0\u30e0\u306f\u7834\u308c\u307e\u3059\u304c\u3001\u305d\u306e\u5f8c\u306b\u30aa\u30fc\u30d6\u3088\u308a\u53d7\u9818\u3057\u305f \u30b9\u30c8\u30e9\u30a4\u30af\u30d5\u30ea\u30fc\u30c0\u30e0\u30ac\u30f3\u30c0\u30e0 \u3068\u3068\u3082\u306b\u91cd\u8981\u306a\u5f79\u5272\u3092\u62c5\u3046\u4e8b\u306b\u306a\u308a\u307e\u3059\u3002\u30ad\u30e9\u306e\u7acb\u5834\u306e\u5909\u5316\u306f\u3001\u6226\u4e89\u3092\u7d4c\u9a13\u3057\u305f\u8005\u3068\u3057\u3066\u306e\u8cac\u4efb\u3068\u3001\u7406\u60f3\u3092\u8ffd\u6c42\u3059\u308b\u59ff\u52e2\u3092\u3088\u308a\u9bae\u660e\u306b\u63cf\u304d\u51fa\u3057\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u4e00\u65b9\u3001\u30a2\u30b9\u30e9\u30f3\u30fb\u30b6\u30e9\u306e\u7acb\u5834\u306f\u3088\u308a\u8907\u96d1\u306b\u5909\u5316\u3057\u307e\u3059\u3002\u5f53\u521d\u3001\u5f7c\u306f\u30aa\u30fc\u30d6\u306b\u3066 \u30ab\u30ac\u30ea\u30fb\u30e6\u30e9\u30fb\u30a2\u30b9\u30cf \u306e\u79d8\u66f8\u3068\u3057\u3066\u767b\u5834\u3057\u307e\u3059\u304c\u3001\u30ae\u30eb\u30d0\u30fc\u30c8\u30fb\u30c7\u30e5\u30e9\u30f3\u30c0\u30eb\u8b70\u9577\u306e\u8aac\u5f97\u306b\u3088\u308aZAFT\u306b\u5fa9\u5e30\u3001\u4f5c\u6226\u58eb\u5b98\u3068\u3057\u3066 \u30bb\u30a4\u30d0\u30fc\u30ac\u30f3\u30c0\u30e0 \u3068\u3068\u3082\u306b\u6d3b\u52d5\u3057\u307e\u3059\u3002\uff08\u203b \u30b8\u30e3\u30b9\u30c6\u30a3\u30b9\u30ac\u30f3\u30c0\u30e0 \u306f\u524d\u4f5c\u3067\u81ea\u7206\u306b\u3088\u308a\u5931\u308f\u308c\u3066\u3044\u307e\u3059\u3002\uff09\u3057\u304b\u3057\u3001\u7269\u8a9e\u304c\u9032\u3080\u306b\u3064\u308c\u3066\u3001\u30c7\u30e5\u30e9\u30f3\u30c0\u30eb\u306e\u771f\u306e\u610f\u56f3\u306b\u7591\u554f\u3092\u62b1\u304f\u3088\u3046\u306b\u306a\u308a\u307e\u3059\u3002\u30a2\u30b9\u30e9\u30f3\u306e\u7acb\u5834\u306e\u5909\u5316\u306f\u3001\u6b63\u7fa9\u3068\u306f\u4f55\u304b\u3001\u8ab0\u306e\u305f\u3081\u306b\u6226\u3046\u3079\u304d\u304b\u3068\u3044\u3046\u554f\u3044\u3092\u89b3\u5ba2\u306b\u6295\u3052\u304b\u3051\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u3053\u308c\u3089\u306e\u5909\u5316\u306b\u3088\u308a\u3001\u30ad\u30e9\u3068\u30a2\u30b9\u30e9\u30f3\u306f\u65b0\u305f\u306a\u8996\u70b9\u304b\u3089\u7269\u8a9e\u306b\u95a2\u308f\u308b\u3053\u3068\u306b\u306a\u308a\u307e\u3059\u3002\u5f7c\u3089\u306e\u6210\u9577\u3068\u845b\u85e4\u306f\u3001\u4f5c\u54c1\u306e\u30c6\u30fc\u30de\u3067\u3042\u308b\u300c\u500b\u4eba\u306e\u4fe1\u5ff5\u3068\u793e\u4f1a\u306e\u79e9\u5e8f\u300d\u3068\u3044\u3046\u554f\u984c\u3092\u3088\u308a\u6df1\u304f\u6398\u308a\u4e0b\u3052\u308b\u5f79\u5272\u3092\u679c\u305f\u3057\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u305f\u3060\u3057\u3001\u5f7c\u3089\u306e\u63cf\u5199\u306b\u306f\u8cdb\u5426\u4e21\u8ad6\u304c\u3042\u308a\u307e\u3059\u3002\u4f8b\u3048\u3070\u3001\u30ad\u30e9\u306e\u63cf\u5199\u304c\u300c\u5b8c\u74a7\u3059\u304e\u308b\u300d\u3068\u3044\u3046\u6279\u5224\u3082\u3042\u308a\u307e\u3059\u3002\u3057\u304b\u3057\u3001\u3053\u306e\u3088\u3046\u306a\u8b70\u8ad6\u3082\u4f5c\u54c1\u306e\u9b45\u529b\u306e\u4e00\u3064\u3068\u8a00\u3048\u308b\u3067\u3057\u3087\u3046\u3002<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E3%83%87%E3%82%B9%E3%83%86%E3%82%A3%E3%83%8B%E3%83%BC%E3%83%97%E3%83%A9%E3%83%B3%E3%81%A8%E3%81%AF%EF%BC%9F%E3%81%9D%E3%81%AE%E7%9B%AE%E7%9A%84%E3%81%A8%E5%BD%B1%E9%9F%BF\"><\/span>\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30d7\u30e9\u30f3\u3068\u306f\uff1f\u305d\u306e\u76ee\u7684\u3068\u5f71\u97ff<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30d7\u30e9\u30f3\u306f\u3001\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u306e\u7269\u8a9e\u306e\u4e2d\u6838\u3092\u6210\u3059\u91cd\u8981\u306a\u6982\u5ff5\u3067\u3059\u3002\u3053\u306e\u30d7\u30e9\u30f3\u306f\u3001PLANT\u306e\u6700\u9ad8\u8a55\u8b70\u4f1a\u8b70\u9577\u3067\u3042\u308b\u30ae\u30eb\u30d0\u30fc\u30c8\u30fb\u30c7\u30e5\u30e9\u30f3\u30c0\u30eb\u304c\u63d0\u5531\u3059\u308b\u3001\u4eba\u985e\u306e\u672a\u6765\u3092\u5de6\u53f3\u3059\u308b\u58ee\u5927\u306a\u69cb\u60f3\u3067\u3059\u3002<\/p>\n\n\n\n<p>\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30d7\u30e9\u30f3\u306e\u76ee\u7684\u306f\u3001\u4eba\u985e\u793e\u4f1a\u306e\u5b8c\u5168\u306a\u7ba1\u7406\u3068\u6700\u9069\u5316\u3067\u3059\u3002\u5177\u4f53\u7684\u306b\u306f\u3001\u5404\u500b\u4eba\u306e\u907a\u4f1d\u5b50\u60c5\u5831\u3092\u5206\u6790\u3057\u3001\u305d\u306e\u80fd\u529b\u306b\u6700\u3082\u9069\u3057\u305f\u8077\u696d\u3084\u793e\u4f1a\u7684\u5f79\u5272\u3092\u5272\u308a\u5f53\u3066\u308b\u3068\u3044\u3046\u3082\u306e\u3067\u3059\u3002\u30c7\u30e5\u30e9\u30f3\u30c0\u30eb\u306f\u3001\u3053\u306e\u30d7\u30e9\u30f3\u306b\u3088\u3063\u3066\u6226\u4e89\u3084\u4e89\u3044\u306e\u306a\u3044\u7406\u60f3\u793e\u4f1a\u304c\u5b9f\u73fe\u3067\u304d\u308b\u3068\u4e3b\u5f35\u3057\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u3057\u304b\u3057\u3001\u3053\u306e\u30d7\u30e9\u30f3\u306b\u306f\u5927\u304d\u306a\u554f\u984c\u70b9\u304c\u3042\u308a\u307e\u3059\u3002\u307e\u305a\u3001\u500b\u4eba\u306e\u81ea\u7531\u610f\u5fd7\u3092\u7121\u8996\u3057\u3066\u3044\u308b\u3068\u3044\u3046\u70b9\u3067\u3059\u3002\u751f\u307e\u308c\u306a\u304c\u3089\u306b\u3057\u3066\u4eba\u751f\u306e\u9032\u8def\u304c\u6c7a\u3081\u3089\u308c\u3066\u3057\u307e\u3046\u305f\u3081\u3001\u500b\u4eba\u306e\u53ef\u80fd\u6027\u3084\u5922\u304c\u5236\u9650\u3055\u308c\u3066\u3057\u307e\u3044\u307e\u3059\u3002\u307e\u305f\u3001\u907a\u4f1d\u5b50\u306b\u3088\u308b\u5dee\u5225\u3092\u52a9\u9577\u3059\u308b\u53ef\u80fd\u6027\u3082\u3042\u308a\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30d7\u30e9\u30f3\u306e\u5f71\u97ff\u306f\u4f5c\u54c1\u5185\u3067\u5927\u304d\u306a\u8b70\u8ad6\u3092\u547c\u3073\u307e\u3059\u3002\u30ad\u30e9\u30fb\u30e4\u30de\u30c8\u305f\u3061\u306f\u3001\u3053\u306e\u30d7\u30e9\u30f3\u306b\u5f37\u304f\u53cd\u5bfe\u3057\u3001\u4eba\u985e\u306e\u81ea\u7531\u3068\u53ef\u80fd\u6027\u3092\u5b88\u308b\u305f\u3081\u306b\u6226\u3044\u307e\u3059\u3002\u4e00\u65b9\u3067\u3001\u30d7\u30e9\u30f3\u3092\u652f\u6301\u3059\u308b\u4eba\u3005\u3082\u591a\u304f\u5b58\u5728\u3057\u3001\u793e\u4f1a\u306e\u5206\u65ad\u3092\u5f15\u304d\u8d77\u3053\u3057\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u3053\u306e\u30d7\u30e9\u30f3\u3092\u901a\u3058\u3066\u3001\u4f5c\u54c1\u306f\u300c\u7406\u60f3\u306e\u793e\u4f1a\u3068\u306f\u4f55\u304b\u300d\u300c\u500b\u4eba\u306e\u81ea\u7531\u3068\u793e\u4f1a\u306e\u79e9\u5e8f\u306e\u30d0\u30e9\u30f3\u30b9\u3092\u3069\u3046\u53d6\u308b\u3079\u304d\u304b\u300d\u3068\u3044\u3046\u6df1\u3044\u554f\u3044\u3092\u6295\u3052\u304b\u3051\u3066\u3044\u307e\u3059\u3002\u8996\u8074\u8005\u81ea\u8eab\u3082\u3053\u306e\u554f\u984c\u306b\u3064\u3044\u3066\u8003\u3048\u3055\u305b\u3089\u308c\u308b\u3001\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u306e\u91cd\u8981\u306a\u30c6\u30fc\u30de\u306e\u4e00\u3064\u3068\u8a00\u3048\u308b\u3067\u3057\u3087\u3046\u3002<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E6%9C%80%E6%96%B0%E9%8B%AD%E3%83%A2%E3%83%93%E3%83%AB%E3%82%B9%E3%83%BC%E3%83%84%E3%81%AF%E3%81%A9%E3%81%AE%E3%82%88%E3%81%86%E3%81%AB%E6%B4%BB%E8%BA%8D%E3%81%99%E3%82%8B%E3%81%AE%E3%81%8B%EF%BC%9F\"><\/span>\u6700\u65b0\u92ed\u30e2\u30d3\u30eb\u30b9\u30fc\u30c4\u306f\u3069\u306e\u3088\u3046\u306b\u6d3b\u8e8d\u3059\u308b\u306e\u304b\uff1f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u3067\u306f\u3001\u6700\u65b0\u92ed\u306e\u30e2\u30d3\u30eb\u30b9\u30fc\u30c4\u304c\u7269\u8a9e\u306e\u5c55\u958b\u306b\u91cd\u8981\u306a\u5f79\u5272\u3092\u679c\u305f\u3057\u307e\u3059\u3002\u3053\u308c\u3089\u306e\u6a5f\u4f53\u306f\u3001\u5358\u306a\u308b\u5175\u5668\u3068\u3057\u3066\u3060\u3051\u3067\u306a\u304f\u3001\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u306e\u6210\u9577\u3084\u7269\u8a9e\u306e\u30c6\u30fc\u30de\u3092\u8868\u73fe\u3059\u308b\u91cd\u8981\u306a\u8981\u7d20\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u4e3b\u4eba\u516c\u30b7\u30f3\u30fb\u30a2\u30b9\u30ab\u304c\u64cd\u7e26\u3059\u308b\u300c\u30a4\u30f3\u30d1\u30eb\u30b9\u30ac\u30f3\u30c0\u30e0\u300d\u306f\u3001\u7279\u306b\u5370\u8c61\u7684\u306a\u6a5f\u4f53\u306e\u4e00\u3064\u3067\u3059\u3002\u3053\u306e\u6a5f\u4f53\u306f\u3001\u6226\u5f8c\u306e\u6838\u8ecd\u7e2e\u6761\u7d04\u306e\u629c\u3051\u9053\u3068\u3057\u3066\u8a66\u4f5c\u3055\u308c\u305f\u30c7\u30e5\u30fc\u30c8\u30ea\u30aa\u30f3\u30d3\u30fc\u30e0\u306b\u3088\u308b\u9060\u9694\u7d66\u96fb\u6a5f\u80fd\u3092\u4ed8\u4e0e\u3055\u308c\u305f\u6a5f\u4f53\u3067\u3001\u8907\u6570\u306e\u30d1\u30fc\u30c4\u306b\u5206\u304b\u308c\u3066\u51fa\u6483\u3057\u3001\u6226\u95d8\u76f4\u524d\u306b\u5408\u4f53\u3059\u308b\u3068\u3044\u3046\u7279\u5fb4\u3092\u6301\u3063\u3066\u3044\u307e\u3059\u3002<br>\u3053\u306e\u72ec\u7279\u306e\u6a5f\u69cb\u306f\u3001\u30b7\u30f3\u306e\u67d4\u8edf\u306a\u6226\u95d8\u30b9\u30bf\u30a4\u30eb\u3092\u8868\u73fe\u3059\u308b\u3068\u3068\u3082\u306b\u3001\u30b7\u30ea\u30fc\u30ba\u5f8c\u534a\u3067\u306e\u6838\u52d5\u529b\u642d\u8f09\u306e\u30cb\u30e5\u30fc\u30c8\u30ed\u30f3\u30b8\u30e3\u30de\u30fc\u30ad\u30e3\u30f3\u30bb\u30e9\u30fc\u6a5f\u3067\u3042\u308b\u300c\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30ac\u30f3\u30c0\u30e0\u300d\u3078\u306e\u4e57\u308a\u63db\u3048\u306f\u5f7c\u81ea\u8eab\u306e\u6210\u9577\u3092\u8c61\u5fb4\u3057\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u307e\u305f\u3001\u30ad\u30e9\u30fb\u30e4\u30de\u30c8\u304c\u64cd\u7e26\u3059\u308b\u300c\u30d5\u30ea\u30fc\u30c0\u30e0\u30ac\u30f3\u30c0\u30e0\u300d\u3068\u305d\u306e\u5f8c\u7d99\u6a5f\u300c\u30b9\u30c8\u30e9\u30a4\u30af\u30d5\u30ea\u30fc\u30c0\u30e0\u30ac\u30f3\u30c0\u30e0\u300d\u3082\u3001\u4eca\u4f5c\u3092\u4ee3\u8868\u3059\u308b\u6a5f\u4f53\u3067\u3059\u3002\u3053\u308c\u3089\u306e\u6a5f\u4f53\u306f\u3001\u9ad8\u3044\u6a5f\u52d5\u529b\u3068\u5f37\u529b\u306a\u6b66\u88c5\u3092\u6301\u3061\u3001\u30ad\u30e9\u306e\u5e73\u548c\u3092\u5b88\u308b\u3068\u3044\u3046\u610f\u5fd7\u3092\u4f53\u73fe\u3057\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u3055\u3089\u306b\u3001\u30a2\u30b9\u30e9\u30f3\u30fb\u30b6\u30e9\u304c\u4f7f\u7528\u3059\u308b\u300c\u30bb\u30a4\u30d0\u30fc\u30ac\u30f3\u30c0\u30e0\u300d\u3084\u300c\u30a4\u30f3\u30d5\u30a3\u30cb\u30c3\u30c8\u30fb\u30b8\u30e3\u30b9\u30c6\u30a3\u30b9\u30ac\u30f3\u30c0\u30e0\u300d\u3082\u3001\u5f7c\u306e\u7acb\u5834\u306e\u5909\u5316\u3084\u845b\u85e4\u3092\u8868\u73fe\u3059\u308b\u91cd\u8981\u306a\u8981\u7d20\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u3053\u308c\u3089\u306e\u6700\u65b0\u92ed\u30e2\u30d3\u30eb\u30b9\u30fc\u30c4\u306f\u3001\u8feb\u529b\u3042\u308b\u6226\u95d8\u30b7\u30fc\u30f3\u3092\u901a\u3058\u3066\u7269\u8a9e\u3092\u76db\u308a\u4e0a\u3052\u307e\u3059\u3002\u4f8b\u3048\u3070\u3001\u5b87\u5b99\u7a7a\u9593\u3084\u5730\u4e0a\u3067\u306e\u9ad8\u901f\u6226\u95d8\u3001\u591a\u6570\u306e\u6575\u3092\u76f8\u624b\u306b\u3057\u305f\u58ee\u7d76\u306a\u6226\u3044\u306a\u3069\u3001\u69d8\u3005\u306a\u5834\u9762\u3067\u6d3b\u8e8d\u3057\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u305f\u3060\u3057\u3001\u3053\u308c\u3089\u306e\u6a5f\u4f53\u306e\u6027\u80fd\u304c\u9ad8\u3059\u304e\u308b\u3068\u3044\u3046\u6279\u5224\u3082\u3042\u308a\u307e\u3059\u3002\u4e00\u90e8\u306e\u8996\u8074\u8005\u304b\u3089\u306f\u3001\u6226\u95d8\u306e\u30d0\u30e9\u30f3\u30b9\u304c\u5d29\u308c\u3066\u3044\u308b\u3068\u3044\u3046\u6307\u6458\u3082\u3042\u308a\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u3057\u304b\u3057\u3001\u3053\u308c\u3089\u306e\u30e2\u30d3\u30eb\u30b9\u30fc\u30c4\u306f\u5358\u306a\u308b\u6226\u95d8\u30de\u30b7\u30f3\u3067\u306f\u3042\u308a\u307e\u305b\u3093\u3002\u5404\u6a5f\u4f53\u306e\u30c7\u30b6\u30a4\u30f3\u3084\u7279\u5fb4\u306f\u3001\u64cd\u7e26\u8005\u306e\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u6027\u3084\u7269\u8a9e\u306e\u30c6\u30fc\u30de\u3068\u5bc6\u63a5\u306b\u7d50\u3073\u3064\u3044\u3066\u3044\u307e\u3059\u3002\u305d\u306e\u305f\u3081\u3001\u6226\u95d8\u30b7\u30fc\u30f3\u3092\u901a\u3058\u3066\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u306e\u5fc3\u60c5\u3084\u7269\u8a9e\u306e\u5c55\u958b\u3092\u7406\u89e3\u3059\u308b\u624b\u304c\u304b\u308a\u306b\u3082\u306a\u308b\u306e\u3067\u3059\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped coblocks-animate wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\" data-coblocks-animation=\"slideInRight\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"337\" src=\"https:\/\/g-jp.net\/main\/wp-content\/uploads\/mega0193-640x640.jpg\" alt=\"g-jp.net\" class=\"wp-image-337\"\/><figcaption class=\"wp-element-caption\">g-jp.net<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E3%82%AC%E3%83%B3%E3%83%80%E3%83%A0SEED_DESTINY%E3%81%AE%E3%81%82%E3%82%89%E3%81%99%E3%81%98%E3%83%BB%E5%9E%A3%E9%96%93%E8%A6%8B%E3%81%88%E3%82%8B%E6%B7%B1%E5%B1%A4%E3%81%A8%E8%A9%95%E4%BE%A1\"><\/span>\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u306e\u3042\u3089\u3059\u3058\u30fb\u57a3\u9593\u898b\u3048\u308b\u6df1\u5c64\u3068\u8a55\u4fa1<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u4e3b\u8981\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u305f\u3061\u306e\u7acb\u5834\u3084\u4fe1\u5ff5\u304c\u3069\u306e\u3088\u3046\u306b\u5909\u5316\u3057\u305f\u304b<\/li>\n\n\n\n<li>\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30d7\u30e9\u30f3\u306e\u76ee\u7684\u3068\u3001\u305d\u308c\u306b\u5bfe\u3059\u308b\u53cd\u5bfe\u3084\u8cdb\u6210\u306e\u7406\u7531<\/li>\n\n\n\n<li>\u4e3b\u4eba\u516c\u305f\u3061\u304c\u3069\u306e\u3088\u3046\u306a\u6226\u3044\u3092\u901a\u3058\u3066\u6210\u9577\u3057\u3001\u5bfe\u7acb\u3057\u3066\u3044\u304f\u304b<\/li>\n\n\n\n<li>\u7269\u8a9e\u306e\u7d50\u672b\u304c\u3069\u3046\u306a\u308a\u3001\u3069\u306e\u3088\u3046\u306a\u30e1\u30c3\u30bb\u30fc\u30b8\u304c\u8fbc\u3081\u3089\u308c\u3066\u3044\u308b\u304b<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E4%BD%9C%E5%93%81%E3%81%8C%E5%95%8F%E3%81%84%E3%81%8B%E3%81%91%E3%82%8B%E7%A4%BE%E4%BC%9A%E5%95%8F%E9%A1%8C%E3%81%A8%E3%81%AF%EF%BC%9F\"><\/span>\u4f5c\u54c1\u304c\u554f\u3044\u304b\u3051\u308b\u793e\u4f1a\u554f\u984c\u3068\u306f\uff1f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u306f\u3001\u5358\u306a\u308b\u30ed\u30dc\u30c3\u30c8\u30a2\u30cb\u30e1\u306e\u67a0\u3092\u8d85\u3048\u3001\u73fe\u4ee3\u793e\u4f1a\u306b\u3082\u901a\u3058\u308b\u91cd\u8981\u306a\u554f\u984c\u3092\u63d0\u8d77\u3057\u3066\u3044\u307e\u3059\u3002\u3053\u306e\u4f5c\u54c1\u304c\u554f\u3044\u304b\u3051\u308b\u793e\u4f1a\u554f\u984c\u306f\u3001\u8996\u8074\u8005\u306b\u6df1\u3044\u601d\u7d22\u3092\u4fc3\u3059\u91cd\u8981\u306a\u8981\u7d20\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u307e\u305a\u3001\u907a\u4f1d\u5b50\u64cd\u4f5c\u306e\u662f\u975e\u3068\u3044\u3046\u554f\u984c\u304c\u3042\u308a\u307e\u3059\u3002\u4f5c\u54c1\u4e16\u754c\u3067\u306f\u3001\u907a\u4f1d\u5b50\u64cd\u4f5c\u306b\u3088\u3063\u3066\u751f\u307e\u308c\u305f\u300c\u30b3\u30fc\u30c7\u30a3\u30cd\u30fc\u30bf\u30fc\u300d\u3068\u901a\u5e38\u306e\u4eba\u985e\u300c\u30ca\u30c1\u30e5\u30e9\u30eb\u300d\u306e\u5bfe\u7acb\u304c\u63cf\u304b\u308c\u307e\u3059\u3002\u3053\u308c\u306f\u73fe\u5b9f\u4e16\u754c\u306b\u304a\u3051\u308b\u907a\u4f1d\u5b50\u6280\u8853\u306e\u9032\u6b69\u3068\u3001\u305d\u308c\u306b\u4f34\u3046\u502b\u7406\u7684\u554f\u984c\u3092\u53cd\u6620\u3057\u3066\u3044\u307e\u3059\u3002\u4f8b\u3048\u3070\u3001\u907a\u4f1d\u5b50\u64cd\u4f5c\u306b\u3088\u3063\u3066\u751f\u307e\u308c\u305f\u4eba\u3005\u306b\u5bfe\u3059\u308b\u5dee\u5225\u3084\u3001\u907a\u4f1d\u5b50\u60c5\u5831\u306b\u57fa\u3065\u304f\u793e\u4f1a\u5236\u5ea6\u306e\u662f\u975e\u306a\u3069\u3001\u73fe\u4ee3\u793e\u4f1a\u3067\u3082\u8b70\u8ad6\u3055\u308c\u3066\u3044\u308b\u554f\u984c\u304c\u542b\u307e\u308c\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u6b21\u306b\u3001\u6226\u4e89\u3068\u5e73\u548c\u306e\u554f\u984c\u304c\u3042\u308a\u307e\u3059\u3002\u4f5c\u54c1\u3067\u306f\u3001\u6226\u4e89\u306e\u60b2\u60e8\u3055\u3068\u5e73\u548c\u306e\u5c0a\u3055\u304c\u7e70\u308a\u8fd4\u3057\u63cf\u304b\u308c\u307e\u3059\u3002\u7279\u306b\u3001\u4e3b\u4eba\u516c\u30b7\u30f3\u30fb\u30a2\u30b9\u30ab\u306e\u7d4c\u9a13\u3092\u901a\u3058\u3066\u3001\u6226\u4e89\u304c\u500b\u4eba\u306b\u4e0e\u3048\u308b\u5f71\u97ff\u3084\u3001\u5e73\u548c\u3092\u5b9f\u73fe\u3059\u308b\u3053\u3068\u306e\u96e3\u3057\u3055\u304c\u793a\u3055\u308c\u3066\u3044\u307e\u3059\u3002\u3053\u308c\u306f\u3001\u73fe\u5b9f\u4e16\u754c\u306e\u7d1b\u4e89\u3084\u56fd\u969b\u95a2\u4fc2\u306b\u3082\u901a\u3058\u308b\u554f\u984c\u3067\u3059\u3002<\/p>\n\n\n\n<p>\u3055\u3089\u306b\u3001\u300c\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30d7\u30e9\u30f3\u300d\u3092\u901a\u3058\u3066\u3001\u500b\u4eba\u306e\u81ea\u7531\u3068\u793e\u4f1a\u306e\u79e9\u5e8f\u306e\u30d0\u30e9\u30f3\u30b9\u3068\u3044\u3046\u554f\u984c\u304c\u63d0\u8d77\u3055\u308c\u307e\u3059\u3002\u3053\u306e\u30d7\u30e9\u30f3\u306f\u3001\u907a\u4f1d\u5b50\u60c5\u5831\u306b\u57fa\u3065\u3044\u3066\u500b\u4eba\u306e\u8077\u696d\u3084\u793e\u4f1a\u7684\u5f79\u5272\u3092\u6c7a\u5b9a\u3059\u308b\u3068\u3044\u3046\u3082\u306e\u3067\u3059\u3002\u3053\u308c\u306f\u3001\u52b9\u7387\u7684\u306a\u793e\u4f1a\u30b7\u30b9\u30c6\u30e0\u3068\u500b\u4eba\u306e\u81ea\u7531\u610f\u5fd7\u306e\u3069\u3061\u3089\u3092\u512a\u5148\u3059\u3079\u304d\u304b\u3068\u3044\u3046\u3001\u73fe\u4ee3\u793e\u4f1a\u3067\u3082\u8b70\u8ad6\u3055\u308c\u3066\u3044\u308b\u554f\u984c\u3092\u53cd\u6620\u3057\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u3053\u308c\u3089\u306e\u554f\u984c\u63d0\u8d77\u306b\u3088\u308a\u3001\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u306f\u8996\u8074\u8005\u306b\u73fe\u4ee3\u793e\u4f1a\u306e\u8ab2\u984c\u306b\u3064\u3044\u3066\u8003\u3048\u308b\u6a5f\u4f1a\u3092\u63d0\u4f9b\u3057\u3066\u3044\u307e\u3059\u3002\u305f\u3060\u3057\u3001\u3053\u308c\u3089\u306e\u554f\u984c\u306e\u6271\u3044\u304c\u8868\u9762\u7684\u3067\u3042\u308b\u3068\u3044\u3046\u6279\u5224\u3082\u3042\u308a\u307e\u3059\u3002\u3057\u304b\u3057\u3001\u30a2\u30cb\u30e1\u3068\u3044\u3046\u5a92\u4f53\u3092\u901a\u3058\u3066\u3053\u308c\u3089\u306e\u554f\u984c\u306b\u89e6\u308c\u308b\u3053\u3068\u3067\u3001\u82e5\u3044\u4e16\u4ee3\u3082\u542b\u3081\u305f\u5e45\u5e83\u3044\u5c64\u306b\u793e\u4f1a\u554f\u984c\u3078\u306e\u95a2\u5fc3\u3092\u559a\u8d77\u3059\u308b\u52b9\u679c\u304c\u3042\u308b\u3068\u8a00\u3048\u308b\u3067\u3057\u3087\u3046\u3002<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E3%81%AA%E3%81%9C%E8%A9%95%E4%BE%A1%E3%81%8C%E5%88%86%E3%81%8B%E3%82%8C%E3%82%8B%E3%81%AE%E3%81%8B%EF%BC%9F%E4%BD%9C%E5%93%81%E3%81%AE%E7%89%B9%E5%BE%B4%E3%81%A8%E6%89%B9%E8%A9%95\"><\/span>\u306a\u305c\u8a55\u4fa1\u304c\u5206\u304b\u308c\u308b\u306e\u304b\uff1f\u4f5c\u54c1\u306e\u7279\u5fb4\u3068\u6279\u8a55<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u306f\u3001\u653e\u9001\u5f53\u6642\u304b\u3089\u73fe\u5728\u306b\u81f3\u308b\u307e\u3067\u3001\u8a55\u4fa1\u304c\u5927\u304d\u304f\u5206\u304b\u308c\u308b\u4f5c\u54c1\u3068\u3057\u3066\u77e5\u3089\u308c\u3066\u3044\u307e\u3059\u3002\u3053\u306e\u8a55\u4fa1\u306e\u5206\u304b\u308c\u76ee\u306b\u306f\u3001\u4f5c\u54c1\u306e\u7279\u5fb4\u3068\u6279\u8a55\u304c\u5bc6\u63a5\u306b\u95a2\u308f\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u307e\u305a\u3001\u7269\u8a9e\u306e\u5c55\u958b\u304c\u8a55\u4fa1\u3092\u5206\u3051\u308b\u5927\u304d\u306a\u8981\u56e0\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002\u5e8f\u76e4\u304b\u3089\u4e2d\u76e4\u306b\u304b\u3051\u3066\u306f\u9ad8\u3044\u8a55\u4fa1\u3092\u5f97\u3066\u3044\u307e\u3057\u305f\u304c\u3001\u5f8c\u534a\u306b\u306a\u308b\u306b\u3064\u308c\u3066\u5c55\u958b\u304c\u6025\u306b\u306a\u308a\u3001\u307e\u3068\u307e\u308a\u304c\u306a\u304f\u306a\u3063\u305f\u3068\u3044\u3046\u6307\u6458\u304c\u3042\u308a\u307e\u3059\u3002\u4f8b\u3048\u3070\u3001\u4e3b\u4eba\u516c\u306e\u7acb\u5834\u304c\u5927\u304d\u304f\u5909\u5316\u3057\u305f\u308a\u3001\u91cd\u8981\u306a\u51fa\u6765\u4e8b\u304c\u5510\u7a81\u306b\u8d77\u3053\u3063\u305f\u308a\u3059\u308b\u5c55\u958b\u306b\u3001\u9055\u548c\u611f\u3092\u899a\u3048\u308b\u8996\u8074\u8005\u304c\u591a\u304b\u3063\u305f\u306e\u3067\u3059\u3002<\/p>\n\n\n\n<p>\u6b21\u306b\u3001\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u306e\u63cf\u5199\u3082\u8a55\u4fa1\u304c\u5206\u304b\u308c\u308b\u70b9\u3067\u3059\u3002\u7279\u306b\u3001\u524d\u4f5c\u300cSEED\u300d\u304b\u3089\u306e\u767b\u5834\u4eba\u7269\u3001\u30ad\u30e9\u30fb\u30e4\u30de\u30c8\u3068\u30e9\u30af\u30b9\u30fb\u30af\u30e9\u30a4\u30f3\u306e\u63cf\u5199\u304c\u300c\u5b8c\u74a7\u3059\u304e\u308b\u300d\u3068\u3044\u3046\u6279\u5224\u304c\u3042\u308a\u307e\u3059\u3002\u4e00\u65b9\u3067\u3001\u65b0\u4e3b\u4eba\u516c\u30b7\u30f3\u30fb\u30a2\u30b9\u30ab\u306e\u6210\u9577\u904e\u7a0b\u304c\u5341\u5206\u306b\u63cf\u304b\u308c\u3066\u3044\u306a\u3044\u3068\u3044\u3046\u6307\u6458\u3082\u3042\u308a\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u307e\u305f\u3001\u4f5c\u54c1\u306e\u30c6\u30fc\u30de\u6027\u3082\u8a55\u4fa1\u304c\u5206\u304b\u308c\u308b\u8981\u56e0\u3067\u3059\u3002\u793e\u4f1a\u554f\u984c\u3084\u653f\u6cbb\u7684\u30c6\u30fc\u30de\u3092\u6271\u3063\u3066\u3044\u308b\u70b9\u306f\u8a55\u4fa1\u3055\u308c\u3066\u3044\u307e\u3059\u304c\u3001\u305d\u306e\u6398\u308a\u4e0b\u3052\u65b9\u304c\u4e0d\u5341\u5206\u3060\u3068\u3044\u3046\u6279\u5224\u3082\u3042\u308a\u307e\u3059\u3002\u7279\u306b\u300c\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30d7\u30e9\u30f3\u300d\u3068\u3044\u3046\u91cd\u8981\u306a\u6982\u5ff5\u306e\u662f\u975e\u306b\u3064\u3044\u3066\u306e\u8b70\u8ad6\u304c\u4e0d\u8db3\u3057\u3066\u3044\u308b\u3068\u3044\u3046\u610f\u898b\u304c\u3042\u308a\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u4e00\u65b9\u3067\u3001\u4f5c\u54c1\u306e\u9b45\u529b\u3068\u3057\u3066\u9ad8\u304f\u8a55\u4fa1\u3055\u308c\u3066\u3044\u308b\u70b9\u3082\u3042\u308a\u307e\u3059\u3002\u7f8e\u9e97\u306a\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u30c7\u30b6\u30a4\u30f3\u3084\u8feb\u529b\u3042\u308b\u6226\u95d8\u30b7\u30fc\u30f3\u3001\u5370\u8c61\u7684\u306a\u97f3\u697d\u306a\u3069\u306f\u3001\u591a\u304f\u306e\u8996\u8074\u8005\u304b\u3089\u652f\u6301\u3092\u5f97\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u3053\u306e\u3088\u3046\u306b\u8a55\u4fa1\u304c\u5206\u304b\u308c\u308b\u7406\u7531\u3068\u3057\u3066\u3001\u5236\u4f5c\u80cc\u666f\u3082\u5f71\u97ff\u3057\u3066\u3044\u307e\u3059\u3002\u5236\u4f5c\u30b9\u30b1\u30b8\u30e5\u30fc\u30eb\u306e\u554f\u984c\u304b\u3089\u3001\u5f8c\u534a\u306e\u5c55\u958b\u304c\u6025\u306b\u306a\u3063\u305f\u3068\u3044\u3046\u6307\u6458\u304c\u3042\u308a\u307e\u3059\u3002\u307e\u305f\u3001\u524d\u4f5c\u306e\u4eba\u6c17\u3092\u610f\u8b58\u3057\u3059\u304e\u305f\u3053\u3068\u3067\u3001\u65b0\u3057\u3044\u8981\u7d20\u3068\u65e7\u6765\u306e\u8981\u7d20\u306e\u30d0\u30e9\u30f3\u30b9\u304c\u53d6\u308c\u306a\u304b\u3063\u305f\u3068\u3044\u3046\u898b\u65b9\u3082\u3042\u308a\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u7d50\u679c\u3068\u3057\u3066\u3001\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u306f\u8cdb\u5426\u4e21\u8ad6\u3092\u547c\u3076\u4f5c\u54c1\u3068\u306a\u308a\u307e\u3057\u305f\u3002\u3057\u304b\u3057\u3001\u3053\u306e\u8a55\u4fa1\u306e\u5206\u304b\u308c\u76ee\u3053\u305d\u304c\u3001\u4f5c\u54c1\u306e\u5965\u6df1\u3055\u3092\u7269\u8a9e\u3063\u3066\u3044\u308b\u3068\u3082\u8a00\u3048\u308b\u3067\u3057\u3087\u3046\u3002\u8996\u8074\u8005\u305d\u308c\u305e\u308c\u304c\u81ea\u5206\u306a\u308a\u306e\u89e3\u91c8\u3068\u697d\u3057\u307f\u65b9\u3092\u898b\u51fa\u305b\u308b\u3001\u591a\u9762\u7684\u306a\u9b45\u529b\u3092\u6301\u3064\u4f5c\u54c1\u306a\u306e\u3067\u3059\u3002<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E9%9F%B3%E6%A5%BD%E3%81%A8%E5%A3%B0%E5%84%AA%E9%99%A3%E3%81%AF%E3%81%A9%E3%81%AE%E3%82%88%E3%81%86%E3%81%AB%E4%BD%9C%E5%93%81%E3%82%92%E5%BD%A9%E3%82%8B%E3%81%AE%E3%81%8B%EF%BC%9F\"><\/span>\u97f3\u697d\u3068\u58f0\u512a\u9663\u306f\u3069\u306e\u3088\u3046\u306b\u4f5c\u54c1\u3092\u5f69\u308b\u306e\u304b\uff1f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u306b\u304a\u3044\u3066\u3001\u97f3\u697d\u3068\u58f0\u512a\u9663\u306f\u4f5c\u54c1\u306e\u9b45\u529b\u3092\u5927\u304d\u304f\u9ad8\u3081\u308b\u91cd\u8981\u306a\u8981\u7d20\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002\u3053\u308c\u3089\u306e\u8981\u7d20\u304c\u3001\u7269\u8a9e\u306e\u5c55\u958b\u3084\u611f\u60c5\u8868\u73fe\u3092\u3088\u308a\u8c4a\u304b\u306b\u3057\u3001\u8996\u8074\u8005\u306e\u5fc3\u306b\u6df1\u304f\u97ff\u304f\u4f5c\u54c1\u306b\u4ed5\u4e0a\u3052\u3066\u3044\u308b\u306e\u3067\u3059\u3002<\/p>\n\n\n\n<p>\u307e\u305a\u3001\u97f3\u697d\u9762\u3067\u306f\u3001\u4f50\u6a4b\u4fca\u5f66\u6c0f\u306b\u3088\u308b\u58ee\u5927\u306a\u30aa\u30fc\u30b1\u30b9\u30c8\u30e9\u30b5\u30a6\u30f3\u30c9\u304c\u7279\u7b46\u3055\u308c\u307e\u3059\u3002\u6226\u95d8\u30b7\u30fc\u30f3\u3067\u306e\u8feb\u529b\u3042\u308b\u66f2\u3084\u3001\u611f\u52d5\u7684\u306a\u5834\u9762\u3067\u306e\u5fc3\u306b\u67d3\u307f\u5165\u308b\u30e1\u30ed\u30c7\u30a3\u30fc\u306a\u3069\u3001\u5834\u9762\u306b\u5408\u308f\u305b\u305f\u591a\u5f69\u306a\u97f3\u697d\u304c\u7269\u8a9e\u3092\u5f69\u308a\u307e\u3059\u3002\u4f8b\u3048\u3070\u3001\u300c\u6681\u306e\u8eca\u300d\u3084\u300c\u899a\u9192\u300d\u3068\u3044\u3063\u305f\u697d\u66f2\u306f\u3001\u591a\u304f\u306e\u30d5\u30a1\u30f3\u306b\u611b\u3055\u308c\u308b\u540d\u66f2\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u307e\u305f\u3001\u30aa\u30fc\u30d7\u30cb\u30f3\u30b0\u30c6\u30fc\u30de\u3084\u30a8\u30f3\u30c7\u30a3\u30f3\u30b0\u30c6\u30fc\u30de\u3082\u5370\u8c61\u7684\u3067\u3059\u3002T.M.Revolution\u306b\u3088\u308b\u300cIGNITED\u300d\u3084\u3001\u7389\u7f6e\u6210\u5b9f\u306b\u3088\u308b\u300cReason\u300d\u306a\u3069\u3001\u6b4c\u8a5e\u3084\u30e1\u30ed\u30c7\u30a3\u30fc\u304c\u4f5c\u54c1\u306e\u30c6\u30fc\u30de\u3068\u898b\u4e8b\u306b\u8abf\u548c\u3057\u3001\u8996\u8074\u8005\u306e\u611f\u60c5\u3092\u9ad8\u3081\u3066\u3044\u307e\u3059\u3002\u3053\u308c\u3089\u306e\u697d\u66f2\u306f\u3001\u30a2\u30cb\u30e1\u306e\u67a0\u3092\u8d85\u3048\u3066\u4eba\u6c17\u3092\u535a\u3057\u3001\u97f3\u697d\u30c1\u30e3\u30fc\u30c8\u3067\u3082\u9ad8\u3044\u8a55\u4fa1\u3092\u5f97\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<p>\u4e00\u65b9\u3001\u58f0\u512a\u9663\u306e\u6f14\u6280\u3082\u4f5c\u54c1\u306e\u9b45\u529b\u3092\u5927\u304d\u304f\u5f15\u304d\u7acb\u3066\u3066\u3044\u307e\u3059\u3002\u4e3b\u4eba\u516c\u30b7\u30f3\u30fb\u30a2\u30b9\u30ab\u5f79\u306e\u9234\u6751\u5065\u4e00\u3055\u3093\u306f\u3001\u8907\u96d1\u306a\u611f\u60c5\u3092\u62b1\u3048\u308b\u4e3b\u4eba\u516c\u3092\u898b\u4e8b\u306b\u6f14\u3058\u5206\u3051\u3066\u3044\u307e\u3059\u3002\u307e\u305f\u3001\u30ad\u30e9\u30fb\u30e4\u30de\u30c8\u5f79\u306e\u4fdd\u5fd7\u7dcf\u4e00\u6717\u3055\u3093\u3084\u3001\u30a2\u30b9\u30e9\u30f3\u30fb\u30b6\u30e9\u5f79\u306e\u77f3\u7530\u5f70\u3055\u3093\u306a\u3069\u3001\u5b9f\u529b\u6d3e\u58f0\u512a\u9663\u304c\u8107\u3092\u56fa\u3081\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u7279\u306b\u3001\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u306e\u6210\u9577\u3084\u845b\u85e4\u3092\u8868\u73fe\u3059\u308b\u5834\u9762\u3067\u306e\u58f0\u512a\u9663\u306e\u71b1\u6f14\u306f\u3001\u8996\u8074\u8005\u306e\u611f\u60c5\u79fb\u5165\u3092\u4fc3\u3057\u3001\u7269\u8a9e\u3078\u306e\u6ca1\u5165\u611f\u3092\u9ad8\u3081\u3066\u3044\u307e\u3059\u3002\u4f8b\u3048\u3070\u3001\u30b7\u30f3\u304c\u904e\u53bb\u306e\u30c8\u30e9\u30a6\u30de\u3068\u5411\u304d\u5408\u3046\u5834\u9762\u3084\u3001\u30ad\u30e9\u3068\u30a2\u30b9\u30e9\u30f3\u304c\u518d\u4f1a\u3059\u308b\u5834\u9762\u306a\u3069\u3001\u58f0\u512a\u306e\u6f14\u6280\u529b\u304c\u7269\u8a9e\u306e\u611f\u52d5\u3092\u500d\u5897\u3055\u305b\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u3055\u3089\u306b\u3001\u30e9\u30af\u30b9\u30fb\u30af\u30e9\u30a4\u30f3\u5f79\u306e\u7530\u4e2d\u7406\u6075\u3055\u3093\u306b\u3088\u308b\u6b4c\u5531\u30b7\u30fc\u30f3\u3082\u3001\u4f5c\u54c1\u306e\u9b45\u529b\u306e\u4e00\u3064\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u30bd\u30f3\u30b0\u304c\u7269\u8a9e\u3068\u5bc6\u63a5\u306b\u7d50\u3073\u3064\u304d\u3001\u4f5c\u54c1\u4e16\u754c\u3092\u3088\u308a\u8c4a\u304b\u306b\u3057\u3066\u3044\u308b\u306e\u3067\u3059\u3002<\/p>\n\n\n\n<p>\u305f\u3060\u3057\u3001\u3053\u308c\u3089\u306e\u8981\u7d20\u304c\u904e\u5270\u306b\u611f\u3058\u3089\u308c\u308b\u3068\u3044\u3046\u6279\u8a55\u3082\u3042\u308a\u307e\u3059\u3002\u97f3\u697d\u304c\u611f\u60c5\u7684\u3059\u304e\u308b\u3001\u58f0\u512a\u306e\u6f14\u6280\u304c\u5927\u3052\u3055\u3060\u3068\u3044\u3046\u6307\u6458\u3082\u3042\u308a\u307e\u3059\u3002\u3057\u304b\u3057\u3001\u591a\u304f\u306e\u8996\u8074\u8005\u306b\u3068\u3063\u3066\u3001\u97f3\u697d\u3068\u58f0\u512a\u9663\u306e\u529b\u306f\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u3092\u5370\u8c61\u6df1\u3044\u4f5c\u54c1\u306b\u3059\u308b\u91cd\u8981\u306a\u8981\u7d20\u3068\u306a\u3063\u3066\u3044\u308b\u306e\u306f\u9593\u9055\u3044\u3042\u308a\u307e\u305b\u3093\u3002<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped coblocks-animate wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\" data-coblocks-animation=\"slideInLeft\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"276\" src=\"https:\/\/g-jp.net\/main\/wp-content\/uploads\/mega01154-640x640.jpg\" alt=\"g-jp.net\" class=\"wp-image-276\"\/><figcaption class=\"wp-element-caption\">g-jp.net<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E3%83%95%E3%82%A1%E3%83%B3%E3%81%AF%E3%81%A9%E3%81%AE%E3%82%88%E3%81%86%E3%81%AB%E4%BD%9C%E5%93%81%E3%82%92%E6%A5%BD%E3%81%97%E3%82%93%E3%81%A7%E3%81%84%E3%82%8B%E3%81%AE%E3%81%8B%EF%BC%9F\"><\/span>\u30d5\u30a1\u30f3\u306f\u3069\u306e\u3088\u3046\u306b\u4f5c\u54c1\u3092\u697d\u3057\u3093\u3067\u3044\u308b\u306e\u304b\uff1f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u306e\u30d5\u30a1\u30f3\u306f\u3001\u69d8\u3005\u306a\u65b9\u6cd5\u3067\u4f5c\u54c1\u3092\u697d\u3057\u3093\u3067\u3044\u307e\u3059\u3002\u307e\u305a\u3001\u591a\u304f\u306e\u30d5\u30a1\u30f3\u304c\u30ac\u30f3\u30c0\u30e0\u30d5\u30a1\u30f3\u30af\u30e9\u30d6\u306b\u52a0\u5165\u3057\u3001\u30a2\u30d7\u30ea\u3092\u901a\u3058\u3066\u52d5\u753b\u3092\u8996\u8074\u3057\u3066\u3044\u307e\u3059\u3002\u3053\u306e\u30a2\u30d7\u30ea\u3067\u306f\u3001\u300c\u30ac\u30f3\u30c0\u30e0\u300d\u30b7\u30ea\u30fc\u30ba\u306e\u52d5\u753b\u304c\u6700\u591a\u30e9\u30a4\u30f3\u30ca\u30c3\u30d7\u3067\u898b\u653e\u984c\u3068\u306a\u3063\u3066\u304a\u308a\u3001PC\u3084Chromecast\u3067\u3082\u697d\u3057\u3080\u3053\u3068\u304c\u3067\u304d\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u307e\u305f\u3001\u30d5\u30a1\u30f3\u306f\u95a2\u9023\u30a4\u30d9\u30f3\u30c8\u306b\u3082\u7a4d\u6975\u7684\u306b\u53c2\u52a0\u3057\u3066\u3044\u307e\u3059\u3002\u4f8b\u3048\u3070\u3001\u300c\u6a5f\u52d5\u6226\u58eb\u30ac\u30f3\u30c0\u30e0SEED FESTIVAL \uff5eFREEDOM \u65b0\u305f\u306a\u672a\u6765\u3078\uff5e\u300d\u306e\u3088\u3046\u306a\u5927\u898f\u6a21\u30a4\u30d9\u30f3\u30c8\u304c\u958b\u50ac\u3055\u308c\u3001\u58f0\u512a\u9663\u306b\u3088\u308b\u30c8\u30fc\u30af\u30b7\u30e7\u30fc\u3084\u751f\u30a2\u30d5\u30ec\u30b3\u306a\u3069\u304c\u884c\u308f\u308c\u3066\u3044\u307e\u3059\u3002\u3053\u308c\u3089\u306e\u30a4\u30d9\u30f3\u30c8\u306f\u3001\u30d5\u30a1\u30f3\u304c\u4f5c\u54c1\u4e16\u754c\u3092\u3088\u308a\u6df1\u304f\u4f53\u9a13\u3057\u3001\u4ed6\u306e\u30d5\u30a1\u30f3\u3068\u4ea4\u6d41\u3059\u308b\u8cb4\u91cd\u306a\u6a5f\u4f1a\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u3055\u3089\u306b\u3001\u30d5\u30a1\u30f3\u306e\u4e2d\u306b\u306f\u4f5c\u54c1\u306e\u6df1\u3044\u8003\u5bdf\u3092\u697d\u3057\u3080\u4eba\u3005\u3082\u3044\u307e\u3059\u3002\u30aa\u30f3\u30e9\u30a4\u30f3\u30d5\u30a9\u30fc\u30e9\u30e0\u3084SNS\u30b0\u30eb\u30fc\u30d7\u3067\u306f\u3001\u4f5c\u54c1\u306e\u30c6\u30fc\u30de\u3084\u767b\u5834\u4eba\u7269\u306e\u52d5\u6a5f\u306b\u3064\u3044\u3066\u71b1\u5fc3\u306a\u8b70\u8ad6\u304c\u4ea4\u308f\u3055\u308c\u3066\u3044\u307e\u3059\u3002\u4f8b\u3048\u3070\u3001\u300c\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30d7\u30e9\u30f3\u300d\u306e\u662f\u975e\u3084\u3001\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u306e\u6210\u9577\u904e\u7a0b\u306b\u3064\u3044\u3066\u3001\u69d8\u3005\u306a\u89e3\u91c8\u304c\u98db\u3073\u4ea4\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u4e00\u65b9\u3067\u3001\u6279\u8a55\u7684\u306a\u8996\u70b9\u3092\u6301\u3064\u30d5\u30a1\u30f3\u3082\u5b58\u5728\u3057\u307e\u3059\u3002\u4f5c\u54c1\u306e\u8a55\u4fa1\u304c\u5206\u304b\u308c\u308b\u7406\u7531\u3092\u5206\u6790\u3057\u305f\u308a\u3001\u30b9\u30c8\u30fc\u30ea\u30fc\u5c55\u958b\u3084\u6f14\u51fa\u306b\u3064\u3044\u3066\u5efa\u8a2d\u7684\u306a\u6279\u8a55\u3092\u884c\u3063\u305f\u308a\u3057\u3066\u3044\u307e\u3059\u3002\u3053\u308c\u3089\u306e\u8b70\u8ad6\u306f\u3001\u4f5c\u54c1\u306e\u9b45\u529b\u3092\u3088\u308a\u6df1\u304f\u7406\u89e3\u3059\u308b\u3053\u3068\u306b\u3064\u306a\u304c\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u305f\u3060\u3057\u3001\u4e00\u90e8\u306e\u30d5\u30a1\u30f3\u306e\u9593\u3067\u306f\u3001\u4f5c\u54c1\u306e\u8a55\u4fa1\u3092\u3081\u3050\u3063\u3066\u5bfe\u7acb\u304c\u751f\u3058\u308b\u3053\u3068\u3082\u3042\u308a\u307e\u3059\u3002\u7279\u306b\u3001\u5f8c\u534a\u306e\u5c55\u958b\u3084\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u306e\u63cf\u5199\u306b\u3064\u3044\u3066\u610f\u898b\u304c\u5206\u304b\u308c\u308b\u3053\u3068\u304c\u3042\u308a\u307e\u3059\u3002\u3057\u304b\u3057\u3001\u3053\u306e\u3088\u3046\u306a\u8b70\u8ad6\u3082\u4f5c\u54c1\u306e\u5965\u6df1\u3055\u3092\u793a\u3059\u4e00\u3064\u306e\u8a3c\u3068\u8a00\u3048\u308b\u3067\u3057\u3087\u3046\u3002<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E9%96%A2%E9%80%A3%E5%95%86%E5%93%81%E3%81%AB%E3%81%AF%E3%81%A9%E3%81%AE%E3%82%88%E3%81%86%E3%81%AA%E3%82%82%E3%81%AE%E3%81%8C%E3%81%82%E3%82%8B%E3%81%AE%E3%81%8B%EF%BC%9F\"><\/span>\u95a2\u9023\u5546\u54c1\u306b\u306f\u3069\u306e\u3088\u3046\u306a\u3082\u306e\u304c\u3042\u308b\u306e\u304b\uff1f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u306e\u95a2\u9023\u5546\u54c1\u306f\u591a\u5c90\u306b\u308f\u305f\u308a\u3001\u30d5\u30a1\u30f3\u306e\u69d8\u3005\u306a\u30cb\u30fc\u30ba\u306b\u5fdc\u3048\u3066\u3044\u307e\u3059\u3002\u4e2d\u3067\u3082\u7279\u306b\u4eba\u6c17\u304c\u9ad8\u3044\u306e\u304c\u30ac\u30f3\u30d7\u30e9\uff08\u30ac\u30f3\u30c0\u30e0\u306e\u30d7\u30e9\u30e2\u30c7\u30eb\uff09\u3067\u3059\u3002<\/p>\n\n\n\n<p>\u30ac\u30f3\u30d7\u30e9\u306b\u306f\u3001\u521d\u5fc3\u8005\u5411\u3051\u306eHG\u30b7\u30ea\u30fc\u30ba\u304b\u3089\u3001\u7cbe\u5de7\u306a\u4f5c\u308a\u306eMG\u30b7\u30ea\u30fc\u30ba\u3001\u3055\u3089\u306b\u9ad8\u7d1a\u5fd7\u5411\u306ePG\u30b7\u30ea\u30fc\u30ba\u307e\u3067\u3001\u69d8\u3005\u306a\u30b0\u30ec\u30fc\u30c9\u304c\u7528\u610f\u3055\u308c\u3066\u3044\u307e\u3059\u3002\u4f8b\u3048\u3070\u3001\u4e3b\u4eba\u516c\u30b7\u30f3\u30fb\u30a2\u30b9\u30ab\u304c\u642d\u4e57\u3059\u308b\u300c\u30a4\u30f3\u30d1\u30eb\u30b9\u30ac\u30f3\u30c0\u30e0\u300d\u3084\u3001\u30ad\u30e9\u30fb\u30e4\u30de\u30c8\u306e\u300c\u30b9\u30c8\u30e9\u30a4\u30af\u30d5\u30ea\u30fc\u30c0\u30e0\u30ac\u30f3\u30c0\u30e0\u300d\u306a\u3069\u304c\u4eba\u6c17\u30e2\u30c7\u30eb\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u97f3\u697dCD\u3082\u91cd\u8981\u306a\u95a2\u9023\u5546\u54c1\u306e\u4e00\u3064\u3067\u3059\u3002\u30aa\u30fc\u30d7\u30cb\u30f3\u30b0\u30c6\u30fc\u30de\u3084\u30a8\u30f3\u30c7\u30a3\u30f3\u30b0\u30c6\u30fc\u30de\u306f\u3082\u3061\u308d\u3093\u3001\u5287\u4e2dBGM\u3092\u53ce\u9332\u3057\u305f\u30b5\u30a6\u30f3\u30c9\u30c8\u30e9\u30c3\u30af\u3082\u767a\u58f2\u3055\u308c\u3066\u3044\u307e\u3059\u3002\u7279\u306b\u3001T.M.Revolution\u306b\u3088\u308b\u300cIGNITED\u300d\u3084\u3001See-Saw\u306b\u3088\u308b\u300c\u3042\u3093\u306a\u306b\u4e00\u7dd2\u3060\u3063\u305f\u306e\u306b\u300d\u306a\u3069\u306e\u697d\u66f2\u306f\u3001\u30a2\u30cb\u30e1\u30d5\u30a1\u30f3\u4ee5\u5916\u306b\u3082\u5e83\u304f\u77e5\u3089\u308c\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u3055\u3089\u306b\u3001\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u30b0\u30c3\u30ba\u3082\u8c4a\u5bcc\u306b\u5c55\u958b\u3055\u308c\u3066\u3044\u307e\u3059\u3002T\u30b7\u30e3\u30c4\u3084\u30d0\u30c3\u30b0\u306a\u3069\u306e\u65e5\u7528\u54c1\u304b\u3089\u3001\u30d5\u30a3\u30ae\u30e5\u30a2\u3084\u30a2\u30af\u30ea\u30eb\u30b9\u30bf\u30f3\u30c9\u3068\u3044\u3063\u305f\u30b3\u30ec\u30af\u30bf\u30fc\u30ba\u30a2\u30a4\u30c6\u30e0\u307e\u3067\u3001\u5e45\u5e83\u3044\u5546\u54c1\u304c\u7528\u610f\u3055\u308c\u3066\u3044\u307e\u3059\u3002\u7279\u306b\u3001\u30e9\u30af\u30b9\u30fb\u30af\u30e9\u30a4\u30f3\u3084\u30ab\u30ac\u30ea\u30fb\u30e6\u30e9\u30fb\u30a2\u30b9\u30cf\u306a\u3069\u306e\u4eba\u6c17\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u306e\u30b0\u30c3\u30ba\u306f\u9ad8\u3044\u4eba\u6c17\u3092\u8a87\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u66f8\u7c4d\u95a2\u9023\u3067\u306f\u3001\u8a2d\u5b9a\u8cc7\u6599\u96c6\u3084\u30a2\u30fc\u30c8\u30d6\u30c3\u30af\u306a\u3069\u304c\u767a\u58f2\u3055\u308c\u3066\u3044\u307e\u3059\u3002\u3053\u308c\u3089\u306f\u4f5c\u54c1\u4e16\u754c\u3092\u3088\u308a\u6df1\u304f\u7406\u89e3\u3057\u305f\u3044\u30d5\u30a1\u30f3\u306b\u3068\u3063\u3066\u8cb4\u91cd\u306a\u60c5\u5831\u6e90\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u307e\u305f\u3001\u30b2\u30fc\u30e0\u95a2\u9023\u306e\u5546\u54c1\u3082\u898b\u9003\u305b\u307e\u305b\u3093\u3002\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u306e\u4e16\u754c\u89b3\u3092\u697d\u3057\u3081\u308b\u30d3\u30c7\u30aa\u30b2\u30fc\u30e0\u304c\u8907\u6570\u30ea\u30ea\u30fc\u30b9\u3055\u308c\u3066\u304a\u308a\u3001\u5bb6\u5ead\u7528\u30b2\u30fc\u30e0\u6a5f\u3084\u30b9\u30de\u30fc\u30c8\u30d5\u30a9\u30f3\u5411\u3051\u306b\u5c55\u958b\u3055\u308c\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u305f\u3060\u3057\u3001\u3053\u308c\u3089\u306e\u95a2\u9023\u5546\u54c1\u306e\u4e2d\u306b\u306f\u3001\u9ad8\u984d\u306a\u3082\u306e\u3082\u5c11\u306a\u304f\u3042\u308a\u307e\u305b\u3093\u3002\u7279\u306b\u9650\u5b9a\u7248\u306e\u30ac\u30f3\u30d7\u30e9\u3084\u30d5\u30a3\u30ae\u30e5\u30a2\u306f\u3001\u4e88\u7d04\u304c\u6bba\u5230\u3057\u305f\u308a\u3001\u30d7\u30ec\u30df\u30a2\u304c\u3064\u3044\u305f\u308a\u3059\u308b\u3053\u3068\u3082\u3042\u308a\u307e\u3059\u3002\u30d5\u30a1\u30f3\u306e\u4e2d\u306b\u306f\u3001\u30b3\u30ec\u30af\u30b7\u30e7\u30f3\u306b\u304b\u306a\u308a\u306e\u51fa\u8cbb\u3092\u3057\u3066\u3044\u308b\u4eba\u3082\u3044\u308b\u3088\u3046\u3067\u3059\u3002<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E6%96%B0%E4%BD%9C%E6%98%A0%E7%94%BB%E3%80%8CSEED_FREEDOM%E3%80%8D%E3%81%A7%E4%BD%95%E3%81%8C%E6%8F%8F%E3%81%8B%E3%82%8C%E3%82%8B%E3%81%AE%E3%81%8B%EF%BC%9F\"><\/span>\u65b0\u4f5c\u6620\u753b\u300cSEED FREEDOM\u300d\u3067\u4f55\u304c\u63cf\u304b\u308c\u308b\u306e\u304b\uff1f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u65b0\u4f5c\u6620\u753b\u300c\u6a5f\u52d5\u6226\u58eb\u30ac\u30f3\u30c0\u30e0SEED FREEDOM\u300d\u306f\u3001\u300c\u30ac\u30f3\u30c0\u30e0SEED\u300d\u30b7\u30ea\u30fc\u30ba\u306e\u6700\u65b0\u4f5c\u3068\u3057\u30662024\u5e741\u670826\u65e5\u306b\u516c\u958b\u3055\u308c\u307e\u3057\u305f\u3002\u3053\u306e\u4f5c\u54c1\u306f\u3001\u524d\u4f5c\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u304b\u3089\u7d042\u5e74\u5f8c\u306eC.E.75\u5e74\u3092\u821e\u53f0\u3068\u3057\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u7269\u8a9e\u306f\u3001\u5730\u7403\u9023\u5408\u306e\u52a0\u76df\u56fd\u304b\u3089\u306e\u72ec\u7acb\u3092\u76ee\u6307\u3059\u5c0f\u56fd\u305f\u3061\u306e\u7d1b\u4e89\u3084\u3001\u9023\u5408\u5185\u306b\u6d78\u900f\u3059\u308b\u30b3\u30fc\u30c7\u30a3\u30cd\u30fc\u30bf\u30fc\u6392\u65a5\u56e3\u4f53\u300c\u30d6\u30eb\u30fc\u30b3\u30b9\u30e2\u30b9\u300d\u306b\u3088\u308b\u30c6\u30ed\u6d3b\u52d5\u306a\u3069\u3001\u4f9d\u7136\u3068\u3057\u3066\u7d9a\u304f\u4e89\u3044\u304b\u3089\u59cb\u307e\u308a\u307e\u3059\u3002\u3053\u306e\u72b6\u6cc1\u3092\u93ae\u9759\u5316\u3059\u308b\u305f\u3081\u3001\u30e9\u30af\u30b9\u30fb\u30af\u30e9\u30a4\u30f3\u3092\u521d\u4ee3\u7dcf\u88c1\u3068\u3059\u308b\u4e16\u754c\u5e73\u548c\u76e3\u8996\u6a5f\u69cb\u300c\u30b3\u30f3\u30d1\u30b9\u300d\u304c\u5275\u8a2d\u3055\u308c\u3001\u4e3b\u4eba\u516c\u30ad\u30e9\u30fb\u30e4\u30de\u30c8\u305f\u3061\u304c\u305d\u306e\u4e00\u54e1\u3068\u3057\u3066\u6d3b\u52d5\u3057\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u3057\u304b\u3057\u3001\u30e6\u30fc\u30e9\u30b7\u30a2\u9023\u90a6\u304b\u3089\u72ec\u7acb\u3057\u305f\u65b0\u8208\u56fd\u30d5\u30a1\u30a6\u30f3\u30c7\u30fc\u30b7\u30e7\u30f3\u304c\u3001\u30d6\u30eb\u30fc\u30b3\u30b9\u30e2\u30b9\u306e\u672c\u62e0\u5730\u3078\u306e\u30b3\u30f3\u30d1\u30b9\u306e\u51fa\u52d5\u3092\u8981\u8acb\u3057\u3001\u4e8b\u614b\u306f\u65b0\u305f\u306a\u5c55\u958b\u3092\u898b\u305b\u307e\u3059\u3002\u3053\u306e\u80cc\u5f8c\u306b\u306f\u3001\u304b\u3064\u3066\u306e\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30d7\u30e9\u30f3\u306e\u518d\u958b\u3092\u76ee\u8ad6\u3080\u52e2\u529b\u306e\u5b58\u5728\u304c\u793a\u5506\u3055\u308c\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u6620\u753b\u3067\u306f\u3001\u30ad\u30e9\u30fb\u30e4\u30de\u30c8\u3084\u30a2\u30b9\u30e9\u30f3\u30fb\u30b6\u30e9\u3001\u30b7\u30f3\u30fb\u30a2\u30b9\u30ab\u306a\u3069\u3001\u304a\u306a\u3058\u307f\u306e\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u305f\u3061\u306e\u6d3b\u8e8d\u306f\u3082\u3061\u308d\u3093\u3001\u65b0\u305f\u306a\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u3082\u591a\u6570\u767b\u5834\u3057\u307e\u3059\u3002\u7279\u306b\u3001\u7530\u6751\u3086\u304b\u308a\u3084\u4e0b\u91ce\u7d18\u3001\u4e2d\u6751\u60a0\u4e00\u3068\u3044\u3063\u305f\u4eba\u6c17\u58f0\u512a\u304c\u6f14\u3058\u308b\u65b0\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u305f\u3061\u306e\u5f79\u5272\u306b\u6ce8\u76ee\u304c\u96c6\u307e\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u307e\u305f\u3001\u672c\u4f5c\u3067\u306f\u58ee\u5927\u306a\u5b87\u5b99\u6226\u3084\u3001\u6700\u65b0\u92ed\u306e\u30e2\u30d3\u30eb\u30b9\u30fc\u30c4\u306b\u3088\u308b\u8feb\u529b\u3042\u308b\u6226\u95d8\u30b7\u30fc\u30f3\u304c\u5c55\u958b\u3055\u308c\u307e\u3059\u3002\u7279\u306b\u3001\u65b0\u305f\u306b\u767b\u5834\u3059\u308b\u6226\u8266\u3084\u3001\u9032\u5316\u3092\u9042\u3052\u305f\u30ac\u30f3\u30c0\u30e0\u30bf\u30a4\u30d7\u306e\u30e2\u30d3\u30eb\u30b9\u30fc\u30c4\u306e\u6d3b\u8e8d\u304c\u898b\u3069\u3053\u308d\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u305f\u3060\u3057\u3001\u4e00\u90e8\u306e\u30d5\u30a1\u30f3\u304b\u3089\u306f\u3001\u4f5c\u54c1\u306e\u30c6\u30fc\u30de\u6027\u3084\u7269\u8a9e\u306e\u5c55\u958b\u306b\u5bfe\u3057\u3066\u6279\u5224\u7684\u306a\u610f\u898b\u3082\u51fa\u3066\u3044\u307e\u3059\u3002\u4f8b\u3048\u3070\u3001\u300c\u611b\u300d\u3068\u3044\u3046\u30c6\u30fc\u30de\u306e\u6271\u3044\u65b9\u304c\u6d45\u3044\u3068\u3044\u3046\u6307\u6458\u3084\u3001\u4e00\u90e8\u306e\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u306e\u63cf\u5199\u306b\u9055\u548c\u611f\u3092\u899a\u3048\u308b\u3068\u3044\u3046\u58f0\u3082\u3042\u308a\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u305d\u308c\u3067\u3082\u3001\u300cSEED FREEDOM\u300d\u306f\u516c\u958b\u5f8c\u3001\u30ac\u30f3\u30c0\u30e0\u30b7\u30ea\u30fc\u30ba\u306e\u5287\u5834\u516c\u958b\u4f5c\u54c1\u3068\u3057\u3066No.1\u306e\u8208\u884c\u53ce\u5165\u3092\u8a18\u9332\u3059\u308b\u306a\u3069\u3001\u591a\u304f\u306e\u89b3\u5ba2\u3092\u9b45\u4e86\u3057\u3066\u3044\u307e\u3059\u3002\u30b7\u30ea\u30fc\u30ba\u30d5\u30a1\u30f3\u306f\u3082\u3061\u308d\u3093\u3001\u65b0\u305f\u306a\u89b3\u5ba2\u5c64\u306e\u7372\u5f97\u306b\u3082\u6210\u529f\u3057\u3066\u3044\u308b\u3088\u3046\u3067\u3059\u3002<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E3%80%8C%E3%82%AC%E3%83%B3%E3%83%80%E3%83%A0SEED_DESTINY%E3%80%8D%E3%82%92%E6%A5%BD%E3%81%97%E3%82%80%E3%81%AA%E3%82%89%E2%80%A6\"><\/span>\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u3092\u697d\u3057\u3080\u306a\u3089\u2026<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>\u69d8\u3005\u306a\u30b5\u30d6\u30b9\u30af\u30b5\u30fc\u30d3\u30b9\u3067\u300c\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u300d\u3092\u697d\u3057\u3081\u307e\u3059\u304c\u3001\u69d8\u3005\u6bd4\u8f03\u3057\u305f\u96c6\u5927\u6210\u7684\u306a\u7d50\u8ad6\u3068\u3057\u3066\u3001\u5727\u5012\u7684\u306b\u300cDMM\u306e\u30b5\u30d6\u30b9\u30af\u30ea\u30d7\u30b7\u30e7\u30f3\u30b5\u30fc\u30d3\u30b9\u300d\u304c\u304a\u3059\u3059\u3081\u3067\u3059\u3002<\/p>\n\n\n<p>[DMM]<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E3%82%AC%E3%83%B3%E3%83%80%E3%83%A0_%E3%82%B7%E3%83%BC%E3%83%89_%E3%83%87%E3%82%B9%E3%83%86%E3%82%A3%E3%83%8B%E3%83%BC_%E3%81%82%E3%82%89%E3%81%99%E3%81%98%E3%81%A8%E8%A6%8B%E3%81%A9%E3%81%93%E3%82%8D%E8%A7%A3%E8%AA%AC%EF%BC%81%E4%B8%BB%E8%A6%81%E3%82%AD%E3%83%A3%E3%83%A9%E3%81%AE%E5%A4%89%E5%8C%96%E3%81%A8%E7%89%A9%E8%AA%9E%E3%81%AE%E5%85%A8%E5%AE%B9_%E3%81%BE%E3%81%A8%E3%82%81\"><\/span>\u30ac\u30f3\u30c0\u30e0 \u30b7\u30fc\u30c9 \u30c7\u30b9\u30c6\u30a3\u30cb\u30fc \u3042\u3089\u3059\u3058\u3068\u898b\u3069\u3053\u308d\u89e3\u8aac\uff01\u4e3b\u8981\u30ad\u30e3\u30e9\u306e\u5909\u5316\u3068\u7269\u8a9e\u306e\u5168\u5bb9 \u307e\u3068\u3081<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u821e\u53f0\u306f\u524d\u4f5c\u300c\u30ac\u30f3\u30c0\u30e0SEED\u300d\u304b\u30892\u5e74\u5f8c\u306eC.E.73\u5e74\u306e\u4e16\u754c\u3067\u3001\u8868\u9762\u4e0a\u306e\u5e73\u548c\u306e\u88cf\u306b\u7dca\u5f35\u304c\u7d9a\u304f<\/li>\n\n\n\n<li>\u30b3\u30fc\u30c7\u30a3\u30cd\u30fc\u30bf\u30fc\u3068\u30ca\u30c1\u30e5\u30e9\u30eb\u306e\u5bfe\u7acb\u304c\u7d9a\u304d\u3001\u4e21\u8005\u9593\u306e\u6e9d\u304c\u6df1\u307e\u3063\u3066\u3044\u308b<\/li>\n\n\n\n<li>\u4e3b\u4eba\u516c\u304c\u524d\u4f5c\u306e\u30ad\u30e9\u30fb\u30e4\u30de\u30c8\u304b\u3089\u30b7\u30f3\u30fb\u30a2\u30b9\u30ab\u306b\u4ea4\u4ee3\u3057\u3001\u65b0\u305f\u306a\u8996\u70b9\u3067\u7269\u8a9e\u304c\u9032\u884c\u3059\u308b<\/li>\n\n\n\n<li>\u30b7\u30f3\u30fb\u30a2\u30b9\u30ab\u306f\u524d\u4f5c\u306e\u6226\u4e89\u3067\u5bb6\u65cf\u3092\u5931\u3044\u3001ZAFT\u8ecd\u306b\u52a0\u5165\u3057\u305f\u5c11\u5e74\u5175\u3067\u3042\u308b<\/li>\n\n\n\n<li>\u30b7\u30f3\u306f\u65b0\u578b\u6a5f\u300c\u30a4\u30f3\u30d1\u30eb\u30b9\u30ac\u30f3\u30c0\u30e0\u300d\u306e\u30d1\u30a4\u30ed\u30c3\u30c8\u3068\u3057\u3066\u6226\u3044\u306a\u304c\u3089\u3001\u5185\u306b\u77db\u76fe\u3092\u62b1\u3048\u3066\u3044\u308b<\/li>\n\n\n\n<li>\u30ad\u30e9\u30fb\u30e4\u30de\u30c8\u3068\u30a2\u30b9\u30e9\u30f3\u30fb\u30b6\u30e9\u306f\u8107\u5f79\u7684\u306a\u7acb\u5834\u306b\u306a\u308a\u3064\u3064\u3082\u3001\u5f8c\u534a\u3067\u91cd\u8981\u306a\u5f79\u5272\u3092\u679c\u305f\u3059<\/li>\n\n\n\n<li>\u30c7\u30e5\u30e9\u30f3\u30c0\u30eb\u8b70\u9577\u304c\u63d0\u5531\u3059\u308b\u300c\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30d7\u30e9\u30f3\u300d\u304c\u7269\u8a9e\u306e\u4e2d\u6838\u3092\u62c5\u3046<\/li>\n\n\n\n<li>\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30d7\u30e9\u30f3\u306f\u907a\u4f1d\u5b50\u60c5\u5831\u3067\u500b\u4eba\u306e\u8077\u696d\u3092\u6c7a\u5b9a\u3057\u3001\u4eba\u985e\u306e\u7ba1\u7406\u3092\u76ee\u6307\u3059\u69cb\u60f3<\/li>\n\n\n\n<li>\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30d7\u30e9\u30f3\u306e\u662f\u975e\u3092\u5de1\u308a\u3001\u30ad\u30e9\u3068\u30b7\u30f3\u305f\u3061\u304c\u6fc0\u3057\u304f\u5bfe\u7acb\u3059\u308b<\/li>\n\n\n\n<li>\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30d7\u30e9\u30f3\u306f\u500b\u4eba\u306e\u81ea\u7531\u3092\u5426\u5b9a\u3057\u3001\u652f\u914d\u7684\u306a\u793e\u4f1a\u79e9\u5e8f\u3092\u7bc9\u304f\u70b9\u3067\u554f\u984c\u8996\u3055\u308c\u308b<\/li>\n\n\n\n<li>\u30a4\u30f3\u30d1\u30eb\u30b9\u3001\u30b9\u30c8\u30e9\u30a4\u30af\u30d5\u30ea\u30fc\u30c0\u30e0\u3001\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30ac\u30f3\u30c0\u30e0\u306a\u3069\u6700\u65b0\u92ed\u306eMS\u304c\u591a\u6570\u767b\u5834\u3059\u308b<\/li>\n\n\n\n<li>\u4e3b\u306a\u821e\u53f0\u306f\u5b87\u5b99\u3068\u5730\u7403\u306e\u5404\u5730\u3067\u3001\u58ee\u5927\u306a\u6226\u95d8\u30b7\u30fc\u30f3\u304c\u7e70\u308a\u5e83\u3052\u3089\u308c\u308b<\/li>\n\n\n\n<li>\u30b7\u30f3\u306e\u845b\u85e4\u3084\u6226\u4e89\u306e\u60b2\u60e8\u3055\u3092\u901a\u3058\u3001\u500b\u4eba\u306e\u81ea\u7531\u3068\u793e\u4f1a\u306e\u79e9\u5e8f\u3092\u554f\u3046\u30c6\u30fc\u30de\u3092\u63cf\u3044\u3066\u3044\u308b<\/li>\n\n\n\n<li>\u30ad\u30e9\u3068\u30e9\u30af\u30b9\u306e\u63cf\u5199\u304c\u300c\u5b8c\u74a7\u3059\u304e\u308b\u300d\u3068\u3044\u3046\u6279\u5224\u3092\u53d7\u3051\u308b\u3053\u3068\u3082\u3042\u308b<\/li>\n\n\n\n<li>\u5f8c\u534a\u306e\u5c55\u958b\u304c\u6025\u3059\u304e\u3066\u3001\u7269\u8a9e\u306e\u6574\u5408\u6027\u306b\u5bfe\u3059\u308b\u6279\u5224\u3082\u898b\u3089\u308c\u308b<\/li>\n\n\n\n<li>\u5287\u4e2d\u306e\u97f3\u697d\u3084\u58f0\u512a\u306e\u6f14\u6280\u304c\u7269\u8a9e\u306b\u6df1\u307f\u3092\u4e0e\u3048\u3066\u3044\u308b<\/li>\n\n\n\n<li>\u8996\u8074\u8005\u306b\u6226\u4e89\u3084\u793e\u4f1a\u554f\u984c\u3078\u306e\u7406\u89e3\u3092\u6df1\u3081\u3055\u305b\u308b\u793e\u4f1a\u6d3e\u30a2\u30cb\u30e1\u306e\u4e00\u9762\u3082\u6301\u3064<\/li>\n<\/ul>\n\n\n\n<p>\u30ac\u30f3\u30c0\u30e0\u30b7\u30fc\u30c9\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u3001\u30ac\u30f3\u30c0\u30e0\u30b7\u30fc\u30c9\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u3042\u3089\u3059\u3058\u3001\u30ac\u30f3\u30c0\u30e0SEED\u3001\u30ac\u30f3\u30c0\u30e0SEED\u3042\u3089\u3059\u3058\u3001\u30b7\u30f3\u30a2\u30b9\u30ab\u3001\u30ad\u30e9\u30e4\u30de\u30c8\u3001\u30a2\u30b9\u30e9\u30f3\u30b6\u30e9\u3001\u30c7\u30b9\u30c6\u30a3\u30cb\u30fc\u30d7\u30e9\u30f3\u3001\u30ac\u30f3\u30c0\u30e0\u30b7\u30ea\u30fc\u30ba\u3001\u30a2\u30cb\u30e1\u3042\u3089\u3059\u3058<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u30ac\u30f3\u30c0\u30e0SEED DESTINY\u306e\u3042\u3089\u3059\u3058\u3068\u4e16\u754c\u89b3 \u30ac\u30f3\u30c0\u30e0 \u30b7\u30fc\u30c9 \u30c7\u30b9\u30c6\u30a3\u30cb\u30fc \u306f\u300150\u8a71\u3082\u306e\u9577\u4e01\u5834\u3068\u3044\u3046\u4e8b\u3082\u3042\u308a\u7269\u8a9e\u306e\u5168\u5bb9\u3092\u3042\u308b\u7a0b\u5ea6\u628a\u63e1\u3057\u3066\u304a\u304f\u3053\u3068\u306f\u6642\u9593\u306b\u8ffd\u308f\u308c\u304c\u3061\u306a\u73fe\u4ee3\u751f\u6d3b\u306b\u3068\u3063\u3066\u3001\u3084\u306f\u308a\u6709\u52b9\u304b\u3082\u3057\u308c\u307e\u305b\u3093\u3002\u672c [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":714,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[20],"tags":[22,21,23],"class_list":["post-445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-20","tag-seed","tag-21","tag-23"],"_links":{"self":[{"href":"https:\/\/g-jp.net\/main\/wp-json\/wp\/v2\/posts\/445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/g-jp.net\/main\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/g-jp.net\/main\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/g-jp.net\/main\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/g-jp.net\/main\/wp-json\/wp\/v2\/comments?post=445"}],"version-history":[{"count":34,"href":"https:\/\/g-jp.net\/main\/wp-json\/wp\/v2\/posts\/445\/revisions"}],"predecessor-version":[{"id":577,"href":"https:\/\/g-jp.net\/main\/wp-json\/wp\/v2\/posts\/445\/revisions\/577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/g-jp.net\/main\/wp-json\/wp\/v2\/media\/940"}],"wp:attachment":[{"href":"https:\/\/g-jp.net\/main\/wp-json\/wp\/v2\/media?parent=445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/g-jp.net\/main\/wp-json\/wp\/v2\/categories?post=445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/g-jp.net\/main\/wp-json\/wp\/v2\/tags?post=445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}